{"id":9608,"date":"2015-03-19T22:49:59","date_gmt":"2015-03-19T18:49:59","guid":{"rendered":"http:\/\/bodhi.name\/?page_id=9608"},"modified":"2015-03-19T22:49:59","modified_gmt":"2015-03-19T18:49:59","slug":"chapitre-39","status":"publish","type":"page","link":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/","title":{"rendered":"Chapitre 39"},"content":{"rendered":"<p>Ma derni\u00e8re p\u00eache \u00e0 l\u2019Internet \u2013 un message d\u2019un copain de longue date \u2013 il m\u2019a r\u00e9pondu promptement! \u00a0Super. Il doit rester au travail \u00e0 s\u2019ennuyer et \u00e0 lire son courrier. Il me manque m\u00eame un peu\u2026 Son avis est int\u00e9ressant \u2013 j\u2019ai toujours aim\u00e9 lui parl\u00e9, c\u2019est un gars qui a une bonne formation intellectuelle, il a lu presque tout ce qui est possible au sujet du d\u00e9veloppement spirituel, expert en m\u00e9decine, psychologie, il a tendance \u00e0 r\u00e9fl\u00e9chir hors des sentiers battus, il a \u00e9t\u00e9 donc l\u2019un des premiers \u00e0 qui j\u2019avais \u00e9crit \u00able message de test\u00bb &#8211; sur mes efforts et les id\u00e9es de la pratique de la voie directe. C\u2019est pas maman papa \u2013 c\u2019est une personne qui r\u00e9fl\u00e9chit.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00abSalut, Maya! \u00a0Qu\u2019est-ce que c\u2019est que cette billeves\u00e9e qui t\u2019occupe\u2026 \u00e0 quoi bon tu t\u2019es laiss\u00e9e emporter dans de l\u2019eau trouble pareille? \u00a0Tu \u00e9tais pourtant une fille normale, intelligente\u2026 <\/em><\/p>\n<p><em>Ca vient d\u2019o\u00f9, cette idiotie \u2013 la suppression des \u00e9motions n\u00e9gatives? \u00a0Qui les a appel\u00e9es n\u00e9gatives, et pourquoi? \u00a0Dieu nous a cr\u00e9\u00e9s tels que nous sommes, il faut alors s\u2019accepter soi-m\u00eame tel qu\u2019on est \u2013 voil\u00e0 la voie vers la vraie harmonie, et toi, au lieu de \u00e7a tu proposes de se terroriser soi-m\u00eame! \u00a0Celui qui n\u2019a pas d\u2019\u00e9motions ne provoquera jamais aucune sympathie chez une personne normale. Comment veux-tu qu\u2019une b\u00fbche s\u00e8che et insensible puisse la susciter? \u00a0<\/em><\/p>\n<p><em>L\u2019erreur principale de cette \u00abm\u00e9thode\u00bb est l\u2019introduction voil\u00e9e de la notion du p\u00e9ch\u00e9, du mal, de ce qu\u2019il faut \u00e9liminer, ce dont il faut se d\u00e9barrasser. Donc, si ces \u00absages\u00bb ont d\u00e9fini les soi-disant EN comme quelque chose de n\u00e9gatif et de mal, il ne leur reste rien d\u2019autre alors que nier naturellement le n\u00e9gatif. M\u00eame Bouddha a dit il y a des milliers d\u2019ann\u00e9es que la violence ne peut pas \u00eatre \u00e9limin\u00e9e avec de la violence, mais seulement avec l\u2019amour! \u00a0Toi maintenant au lieu de devenir une personnalit\u00e9 enti\u00e8re, s\u2019\u00e9lever en harmonie (le mot occidental \u00abreligion\u00bb et le mot oriental \u00abyoga\u00bb veulent dire exactement \u00e7a) tu te mets \u00e0 rechercher en toi-m\u00eame des ennemies int\u00e9rieurs, te fendre, patauger dans une analyse r\u00e9gressive et te transformer petit \u00e0 petit en une r\u00e9flexive schizo\u00efde. Il y a deux issus \u00e0 une telle voie: tu deviens soit quelqu\u2019un d\u2019insensible et impitoyable avec une sexualit\u00e9 plut\u00f4t hyper d\u00e9velopp\u00e9e, soit schizo maniaque r\u00e9flexif et en combat \u00e9ternel avec ce qui ne fait qu\u2019augmenter suite \u00e0 ce processus. <\/em><\/p>\n<p><em>J\u2019affirme qu\u2019il n\u2019est pas possible de contr\u00f4ler les \u00e9motions n\u00e9gatives. Et, en g\u00e9n\u00e9ral, entamer la voie spirituelle par le combat avec elles est le comble de la stupidit\u00e9, puisqu\u2019elles ne sont que la forme, les crit\u00e8res secondaires d\u2019un probl\u00e8me int\u00e9rieur. C\u2019est comme traiter l\u2019angine en baissant la fi\u00e8vre, tandis que cette m\u00eame fi\u00e8vre est la lutte de l\u2019organisme contre la maladie moyennant la br\u00fblure de la saloperie int\u00e9rieure. Ca va pour les \u00e9motions aussi \u2013 une \u00e9motion n\u00e9gative ext\u00e9rioris\u00e9e \u00e0 temps est\u00a0un gage du calme int\u00e9rieur. <\/em><\/p>\n<p><em>Commencer sa vie spirituelle par la suppression des \u00e9motions n\u2019est pas seulement inutile mais nuisible, car l\u2019individu se supprimerait \u00e0 l\u2019int\u00e9rieur et renverrait toute cette tension dans son inconscient, ce qui risquerait de provoquer finalement l\u2019\u00e9ruption de la schizophr\u00e9nie et des n\u00e9vroses. <\/em><\/p>\n<p><em>Concernant les soi-disant \u00abr\u00e9alisations sexuelles\u00bb! C\u2019est une grosse\u00a0\u2026de, ce que tu as \u00e9crit par l\u00e0. Ca veut dire alors que pour \u00eatre \u00e9veill\u00e9 il faut devenir d\u2019abord p\u00e9d\u00e9raste, onaniste, partouzeur, sodomite et exhibitionniste! \u00a0Et les mauvais \u00e9l\u00e8ves seront sodomis\u00e9s \u00e0 plusieurs, pour augmenter le niveau de r\u00e9ussite? \u00a0Faites le stock de lubrifiant, mes amis, mais ne m\u2019appelez pas, je ne suis pas un pervers. Et si l\u2019individu est normal, il doit devenir pervers selon ton syst\u00e8me? \u00a0Si la personne doit livrer son cul pour atteindre l\u2019\u00e9veil selon ce syst\u00e8me \u2013 \u00e7a me fait rire, et je me moquerai de ces p\u00e9d\u00e9s. Que les autres les sauvent. Ou alors, pour une femme \u2013 il faut \u00eatre saut\u00e9e par un bataillon de mecs? &#8230; Honn\u00eatement, je ne comprends pas &#8211; est-ce que c\u2019est plus sain? \u00a0Sache que la fiert\u00e9 de l\u2019homme consiste en quantit\u00e9 de femmes qu\u2019il a bais\u00e9es, et celle de la femme est en quantit\u00e9 d\u2019hommes d\u00e9gonfl\u00e9s par elle sur cette voie. <\/em><\/p>\n<p><em>Ce de quoi tu \u00e9cris est un mauvais plagiat d\u2019un tantra classique, primitif et par cons\u00e9quent inefficace, mais il y a une \u00e9cole par l\u00e0, l\u2019exp\u00e9rience de tentatives, et erreurs, et d\u00e9couvertes datant de milliers d\u2019ann\u00e9es, une m\u00e9thodologie scientifique pr\u00e9cise, mais lorsque du vrai porno est servi avec la sauce de la condition n\u00e9cessaire du d\u00e9veloppement spirituel &#8211; c\u2019est le comble. <\/em><\/p>\n<p><em>Si tu veux vraiment apprendre quelque chose de VERIDIQUE sur le sexe \u2013 je te raconterai, je t\u2019ai toujours racont\u00e9 tout ce que tu voulais, pourquoi cette fois-ci tu ne m\u2019as pas demand\u00e9 tout de suite? \u00a0Pourquoi tu t\u2019es fourr\u00e9e dans des trous pourris? \u00a0Le sexe est un acte divin, et, initialement, c\u2019est l\u2019extase de l\u2019union de Siva et Sakti, de ing et yang, Rada et Krishna, le Ciel et la Terre, Lingama et Yoni, Purushi et Prakriti, du f\u00e9minin et du masculin. <\/em><\/p>\n<p><em>M\u00eame la th\u00e9ologie chr\u00e9tienne perverse n\u2019a pas pu se passer de la n\u00e9cessit\u00e9 d\u2019avoir la M\u00e8re de Dieu &#8211; le principe divin f\u00e9minin. La divinit\u00e9 m\u00eame s\u2019est divis\u00e9e en deux points oppos\u00e9s \u2013 f\u00e9minin et masculin \u2013 pour que l\u2019\u00e9volution ait lieu et que la vie naisse moyennant l\u2019union de ces points oppos\u00e9s. L\u2019union et la lutte des oppos\u00e9es. Voil\u00e0. <\/em><\/p>\n<p><em>En outre, il faut savoir que chaque orifice dans le corps humain est un canal d\u2019\u00e9change d\u2019\u00e9nergie avec le Cosmos. L\u2019anus, par exemple, est le canal le plus sale, et un homme, qui utilise un autre homme, salit sont canal\u00a0g\u00e9nital (le p\u00e9nis) \u00e9nerg\u00e9tiquement et d\u00e9sormais il n\u2019aura pas de prog\u00e9niture normale, psychologiquement saine. M\u00eame les enfants d\u2019un p\u00e9d\u00e9 enlev\u00e9s apr\u00e8s la naissance deviennent homos aussi.<\/em><\/p>\n<p><em>On peut dire la m\u00eame chose de la partouse: si Dieu voulait \u00e7a, il aurait cr\u00e9\u00e9 Adam, Ivan et Eve. Et puis l\u2019homme laisse une empreinte \u00e9nerg\u00e9tique invisible sur la femme lors des rapports sexuels. La femme le fait, bien s\u00fbr, aussi, mais \u00e0 un degr\u00e9 inf\u00e9rieur, puisqu\u2019elle est le c\u00f4t\u00e9 r\u00e9ceptif vis-\u00e0-vis du sperme et de l\u2019\u00e9nergie, le c\u00f4t\u00e9 passif. Et maintenant imagine une meuf, sodomis\u00e9e par un mec, bais\u00e9e par un autre, et le troisi\u00e8me le faisant devant \u2013 dans la bouche, et tout \u00e7a en m\u00eame temps. Ca donne une sorte de m\u00e9lange d\u2019un bulldog avec un rhinoc\u00e9ros. Une femme qui a eu beaucoup d\u2019hommes cesse bient\u00f4t d\u2019\u00eatre femme dans le sens \u00e9lev\u00e9 du mot \u2013 elle est laide, m\u00eame en ayant une silhouette de top mod\u00e8le. Elle porte l\u2019empreinte de tous ses mecs, toute leur salet\u00e9. Et une femme ayant plusieurs hommes en m\u00eame temps est d\u2019autant plus laide. Une sorte de Frankenstein \u00e9nerg\u00e9tique. <\/em><\/p>\n<p><em>La joie et les sensations fortes dans la perversion sont procur\u00e9es par la nouveaut\u00e9, la force et le c\u00f4t\u00e9 extr\u00eame des impressions, mais on ne peut m\u00eame pas r\u00eaver de progr\u00e8s spirituel quelconque, car la spiritualit\u00e9 veut dire surpasser l\u2019humain en soi, et toi tu descends \u00e0 un niveau plus bas que les animaux suite \u00e0 ces perversit\u00e9s, puisque m\u00eame les animaux n\u2019ont pas de perversions dans le milieu naturel. <\/em><\/p>\n<p><em>Le triomphe et l\u2019extase de la chair te transforment m\u00eame pas en une chienne, mais pire, plus bas, donc, tout ce que tu as \u00e9crit est du d\u00e9lire d\u2019un esprit fou et pervers, et pas un \u00e9sot\u00e9riste.<\/em><\/p>\n<p><em>Et en r\u00e9alit\u00e9 \u2013 c\u2019est qui que tu as d\u00e9terr\u00e9 par l\u00e0? \u00a0Qui t\u2019a racont\u00e9 de telle baliverne? \u00a0Beaucoup qui, au fond d\u2019eux, envient les bouddhas, ou bien ayant atteint juste un chou\u00efa des sensations \u00e0 peu pr\u00e8s mystiques, se nomment gourous, \u00e9veill\u00e9s, tous seuls, ils le font exclusivement pour leur EGO distingu\u00e9 et pseudo spirituel. Ces gens l\u00e0 sont dangereux pour ceux qui sont innocents et na\u00effs, puisqu\u2019ils les s\u00e9duisent avec de la parole douce et des jouets bon march\u00e9 et de mauvaise qualit\u00e9 des sensations occultes pass\u00e9s pour de l\u2019absolu. <\/em><\/p>\n<p><em>Vous \u00eates ensorcel\u00e9s, tels des chatons aveugles, par le miaou de ce bouddha chat et vous tendez vers lui pour avoir son lait (vers l\u2019\u00e9veil avec son aide en tant que gourou), mais vous ne trouverez que sa queue de mec \u00e0 la place de la t\u00e9tine pour sucer du sperme (la perversion, des maladies psychiques, des illusions, la d\u00e9ception) \u00e0 la place du lait (la spiritualit\u00e9). <\/em><\/p>\n<p><em>Je te dis, Mayka, laisse tomber cette billeves\u00e9e avant qu\u2019il ne t\u2019arrive le malheur, rentre et viens \u00e0 mes s\u00e9minaires, il y a beaucoup de monde int\u00e9ressant et vraiment spirituel chez moi, tu apprendras\u00a0e bon sens\u00bb. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Dire que cette lettre m\u2019a choqu\u00e9e c\u2019est ne rien dire. Je ne comprends rien\u2026 non, ce n\u2019est pas lui qui a \u00e9crit cette lettre\u2026 comment \u00e7a, pas lui, bien s\u00fbr que si. Je me suis rappel\u00e9 son visage \u2013 un gars marrant, loustic, intelligent, aime discuter. Et l\u00e0 UNE TELLE CHOSE!! De la haine, la stupidit\u00e9, l\u2019agressivit\u00e9 sauvage envers la libert\u00e9 sexuelle f\u00e9minine, et en g\u00e9n\u00e9ral, la haine f\u00e9roce envers le sexe. Et c\u2019est quoi qu\u2019il \u00e9crit \u00e0 propos des \u00e9motions n\u00e9gatives? \u00a0Comme s\u2019il n\u2019a rien lu sur ce que j\u2019ai dit concernant la diff\u00e9rence entre \u00absupprimer\u00bb et \u00ab\u00e9liminer\u00bb. Mais c\u2019est une b\u00eate sauvage\u2026 Le plus horrible c\u2019est qu\u2019en r\u00e9alit\u00e9 c\u2019est un gars tout \u00e0 fait normal! \u00a0Qu\u2019est-ce que \u00e7a veut dire \u00aben r\u00e9alit\u00e9\u00bb?? C\u2019est \u00e7a la r\u00e9alit\u00e9! \u00a0C\u2019est celle l\u00e0 et pas les images que j\u2019ai pos\u00e9es sur toutes mes connaissances. Qu\u2019est-ce qui m\u2019emp\u00eachait de lui parler franchement avant? \u00a0Lui poser des questions pour entendre sa VRAI vision de la vie. Le plus horrible c\u2019est que maintenant je ne sais pas \u2013 et si TOUS mes anciens amis n\u2019\u00e9taient que des fant\u00f4mes, que j\u2019ai cr\u00e9\u00e9s moi-m\u00eame? \u00a0Comment vivre maintenant avec les gens, parmi les gens, je ne vois partout que la plong\u00e9e terrible dans la haine, la honte, dans de diverses sortes d\u2019EN?<\/p>\n<p>J\u2019ai eu envie de lui poser encore quelques questions simples, pour voir encore plus clairement \u2013 QUELLE personne j\u2019ai imagin\u00e9e comme normale\u2026 ou bien moi aussi je n\u2019en \u00e9tais pas loin? \u00a0J\u2019ai \u00e9crit. Envoy\u00e9. Je reste l\u00e0. J\u2019attends. Je dig\u00e8re. Je n\u2019arrive pas \u00e0 croire que je ne r\u00eave pas. Je renouvelle la fen\u00eatre \u2013 il y a son message. Et m\u00eame deux! \u00a0J\u2019ai re\u00e7u aussi une lettre de Lenka du sixi\u00e8me \u00e9tage &#8211; elle doit \u00eatre aussi au travail \u00e0 l\u2019ordi \u00e0 s\u2019ennuyer. J\u2019ai m\u00eame peur d\u2019ouvrir son message\u2026 Je vais voir d\u2019abord sa r\u00e9ponse \u00e0 lui\u2026<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00abTu demandes ce que je fais avec les EN? \u00a0Tu aurais d\u00fb me le demander tout de suite au lieu de te foncer la t\u00eate baiss\u00e9e dans une secte. Lorsque les EN ont d\u00e9j\u00e0 apparu, je ne fais rien, je leur permets de se d\u00e9penser, je l\u2019observe et je l\u2019utilise comme une source suppl\u00e9mentaire de l\u2019\u00e9nergie pour agir. Les \u00e9motions ne sont pas un \u00e9pouvantail, mais une force! \u00a0Ca d\u00e9pend de toi o\u00f9 appliquer cette force. A l\u2019amour de Dieu, \u00e0 la haine de l\u2019ennemi, ou bien \u00e0 la haine de soi et les processus naturels en soi \u2013 par exemple, ton soi-disant effort \u00abardent\u00bb &#8211; la haine de sa sph\u00e8re \u00e9motionnelle. C\u2019est l\u2019affaire du go\u00fbt, de l\u2019esprit et de l\u2019\u00e9ducation. <\/em><\/p>\n<p><em>Mes \u00e9motions sont MES \u00e9motions, elles ne peuvent pas g\u00eaner. <\/em><\/p>\n<p><em>Ainsi, quand tu as mal \u00e0 la t\u00eate, elle ne peut pas te g\u00eaner, elle a mal et elle demande du traitement. Mets tout de c\u00f4t\u00e9 et prends soin de ta t\u00eate. Il n\u2019y a rien d\u2019autre de plus important. Tout ou presque tout \u00e0 quoi le mal de t\u00eate peut g\u00eaner n\u2019est pas toi, c\u2019est secondaire, en dehors. Lorsqu\u2019elle (les \u00e9motions) sont pr\u00e9sentes \u2013 c\u2019est pas grave, c\u2019est une r\u00e9ponse \u00e0 la vie, \u00e0 un excitant ext\u00e9rieur. Qu\u2019elles soient, qu\u2019elles vivent en toi, si elles ont apparu. La seule chose n\u00e9cessaire c\u2019est l\u2019attention envers elles. Comme un enfant capricieux demande une grande attention, ainsi les \u00e9motions. Si un enfant est grond\u00e9 tout le temps \u00abfais pas ci, fais pas \u00e7a, qu\u2019on ne t\u2019entende pas, tu ne dois pas te manifester, ta vie est un ph\u00e9nom\u00e8ne malsain\u00bb, etc. \u2013 il grandira un louveteau sauvageon ou un cr\u00e9tin docile \u00e0 tous. <\/em><\/p>\n<p><em>Les enfants font des caprices justement quand ils se sentent oubli\u00e9s, ils essayent alors de faire le plus de bruit possible car ils ont besoin d\u2019attention. Cela concerne nos \u00e9motions et notre conscience en g\u00e9n\u00e9ral: l\u2019esprit et les perceptions ont besoin d\u2019attention ici et maintenant (pourtant l\u2019\u00e9nergie est d\u00e9pens\u00e9e pour des r\u00eaves et des souvenirs \u2013 pour le soi-disant avenir et le pass\u00e9, pour des r\u00eaveries) \u2013 sinon elles se vengent. <\/em><\/p>\n<p><em>Il ne faut rien faire expr\u00e8s, ni gratter ses plaies, donne-leur la lumi\u00e8re de ton attention, elle gu\u00e9rira la douleur, couvrira les plaies, cicatrisera celles qui sont infect\u00e9es rapidement, et, ce qui est le plus important, NATURELLEMENT\u00bb. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Chouette. Bien, je n\u2019ai plus de questions \u2013 je ne r\u00eave point, c\u2019est comme \u00e7a. Je vais voir ce qu\u2019il a r\u00e9pondu \u00e0 la deuxi\u00e8me question \u2013 a-t-il compris que la question est moqueuse, ou l\u2019a-t-il prise au s\u00e9rieux?<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00abTu demandes si l\u2019on peut faire la fellation. Ca veut dire que tu as compris ce que je t\u2019ai dit sur les perversions si tu poses cette question. Il faut essayer d\u2019y voir plus clair, au lieu de s\u2019adonner \u00e0 la d\u00e9bauche. Voyons, voyons. <\/em><\/p>\n<p><em>D\u2019abord \u2013 as-tu eu des relations sexuelles avec ton petit ami? \u00a0Si oui, c\u2019est plus facile. Admettons, vous \u00eates au lit, et l\u00e0 il te dit: \u00abje veux que te la prenne dans ta bouche\u00bb, tu es choqu\u00e9e \u2013 tu as peur de prendre cette grosse et souvent malodorante chose dans la bouche, tu crains l\u2019envie de vomir ( et bien souvent ces craintes se r\u00e9v\u00e8lent justes), tu as honte et tu te sens g\u00ean\u00e9e, tu as peur qu\u2019apr\u00e8s \u00e7a il ne te respectera plus, etc.\u2026. <\/em><\/p>\n<p><em>Premi\u00e8rement, dis-lui tout \u00e7a, il doit savoir que ce n\u2019est pas simplement que tu ne veux pas lui faire plaisir, que le probl\u00e8me n\u2019est pas en lui, pas dans tes sentiments \u00e0 son \u00e9gard, mais en toi. <\/em><\/p>\n<p><em>Ensuite, demande-lui de te faire la m\u00eame chose d\u2019abord. Finalement, c\u2019est qui, qui veut le plus du sexe oral? \u00a0Je t\u2019assure que les femmes aiment \u00e7a pas moins que les hommes. Juste \u00e9tudiez les consignes comment faire, ou si vous n\u2019avez pas honte, posez des questions aux copains. Toute affaire doit \u00eatre accomplie savamment, intelligemment, pour ne pas g\u00e2cher la premi\u00e8re impression. <\/em><\/p>\n<p><em>Bon, admettons il a refus\u00e9 \u2013 tu as tout ton droit de lui refuser aussi, en expliquant que la fellation pour l\u2019homme n\u2019est pas indispensable, comme pour la femme. Finalement, tu n\u2019es pas inf\u00e9rieur, ni pire que lui. Explique de sorte qu\u2019il comprenne que vous \u00eates \u00e9gaux l\u00e0-dessus. Il sera d\u2019accord alors, ou il r\u00e9fl\u00e9chira\u2026 et sera d\u2019accord plus tard. <\/em><\/p>\n<p><em>Alors, s\u2019il est d\u2019accord et te le fera le premier \u2013 tu auras un vrai plaisir, une sensation nouvelle, merveilleuse, et ce sera donc plus facile pour toi de le lui faire par gratitude. Les peurs et les complexes partiront. Ca se passera naturellement, sans contrainte. Mais d\u2019abord entra\u00eene-toi avec au moins un concombre. Ou bien qu\u2019il prenne ton doigt dans sa bouche pour te montrer comment il veut que ce soit fait. <\/em><\/p>\n<p><em>Vous pouvez aussi prendre la position 69 \u2013 vous placer t\u00eate-b\u00eache &#8211; lui sur le dos et toi \u00e0 quatre pattes en t\u2019appuyant sur tes genoux et tes coudes au dessus de lui, mais laisse-le commencer et tu le rattraperas aussit\u00f4t. <\/em><\/p>\n<p><em>En principe, le sexe oral n\u2019est pas sale ( juste il faut bien se laver avant, on peut m\u00eame s\u2019aromatiser, mettre de la cr\u00e8me fra\u00eeche, du lait concentr\u00e9 sur la queue, etc.) <\/em><\/p>\n<p><em>La bouche est une sortie aussi bien qu\u2019une entr\u00e9e. Ses dimensions \u00e9tant compatibles avec le vagin. <\/em><\/p>\n<p><em>Sache pourtant, que ce sexe n\u2019est pas non plus la garantie, ni la voie vers l\u2019\u00e9veil. Tout \u00e7a \u00e0 condition que, en principe, tu ne sois pas contre le sexe oral, qu\u2019il ne te d\u00e9go\u00fbte pas. Et si tu es encore pucelle \u2013 je ne conseille pas de commencer par le sexe oral. La femme est un sujet psychique tr\u00e8s fin, tr\u00e8s susceptible et mall\u00e9able. La premi\u00e8re exp\u00e9rience sexuelle est tr\u00e8s importante, il est primordial qu\u2019elle soit telle que la nature l\u2019a con\u00e7ue \u2013 les parties g\u00e9nitales dans les parties g\u00e9nitales. Mine de rien, le sexe oral, m\u00eame s\u2019il est hygi\u00e9nique, est quand m\u00eame une perversion vis-\u00e0-vis de la nature, quoique la plus innocente. Comme \u00e7a, de l\u2019enfantillage l\u00e9ger. Mais il vaut mieux ne pas le supprimer si tu en as envie. Mets de c\u00f4t\u00e9 la morale et l\u2019opinion publique. C\u2019est rien. En g\u00e9n\u00e9ral, fais comme tu le sens, ne te force pas. Finalement, il vaut mieux rester sans ce gars que nuire \u00e0 son go\u00fbt. Tu auras d\u2019autres gars, pourtant la psych\u00e9 ab\u00eem\u00e9e est difficilement r\u00e9parable. <\/em><\/p>\n<p><em>Tu n\u2019as pas \u00e0 demander aux autres ce qui est bien ou pas. Tu dois rester attentive \u00e0 toi-m\u00eame et suivre ta nature. Si tu as envie, fais-le, mais ne te fais pas d\u2019illusions alors, que tu es normale. Si tu as envie de faire l\u2019amour avec une femme, tu devras accepter que tu sois lesbienne, et comprendre qu\u2019il y a une anomalie en toi, puisque Dieu a cr\u00e9\u00e9 Adam et Eve, et pas Eve et Marousya\u00bb. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En le lisant j\u2019ai ressenti distinctement quelques tr\u00e8s fortes pouss\u00e9es d\u2019envie de vomir. Et c\u2019est DANS TOUT CA qu\u2019il vit? \u00a0Pourtant il a une femme, une amante, des enfants\u2026 Bien\u2026<\/p>\n<p>J\u2019ouvre la lettre de Lenka avec une certaine appr\u00e9hension. Q\u2019est-ce qu\u2019elle m\u2019a fabriqu\u00e9?<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00abSalut, Mayka! \u00a0C\u2019est super que tu r\u00e9apparaisses, sans toi on s\u2019ennuie! \u00a0Tu rentres quand? \u00a0J\u2019ai termin\u00e9 mes \u00e9tudes \u00e0 la fac de psy, maintenant je fais des \u00e9tudes pour \u00eatre psychanalyste, j\u2019irai peut-\u00eatre en France pour faire un stage. Tu peux imaginer \u00e7a? \u00a0C\u2019est quoi que tu m\u2019as \u00e9crit par l\u00e0, je ne pige pas. Tu as d\u00fb picoler ou quoi? \u00a0Bon, ne te prends pas la t\u00eate, je plaisante. J\u2019ai lu ton d\u00e9lire\u2026 Ne m\u2019en veux pas, mais je ne m\u2019attendais pas \u00e0 avoir \u00e7a de toi\u2026 et je vais te dire la chose suivante, ma ch\u00e8re. <\/em><\/p>\n<p><em>On est tous diff\u00e9rents. Et si cette voie directe \u00e0 toi allait vraiment pour ceux chez qui cette \u00e9nergie de souffrance est si profond\u00e9ment concentr\u00e9e et si soigneusement bloqu\u00e9e qu\u2019une lib\u00e9ration \u00e9l\u00e9mentaire et la premi\u00e8re tentative de la diriger (la suppression des EN) provoquaient tout de suite la sensation extatique de lib\u00e9ration qu\u2019on appelle par l\u00e0 l\u2019\u00e9veil. C\u2019est comme courir dix kilom\u00e8tres avec un sac \u00e0 dos, et puis s\u2019assoire se reposer (c\u2019est aussi une super pratique) \u2013 et oui, je me souviens tr\u00e8s bien \u2013 un \u00e9veil complet! \u00a0S\u00e9rieux! \u00a0Ou bien l\u2019histoire d\u2019Adam qui achetait une ch\u00e8vre. C\u2019est-\u00e0-dire ceux qui ont les chaussures qui font mal vont \u00eatre appris chez vous de d\u00e9nouer correctement les lacets. Et moi rien ne me fait mal, je vis tr\u00e8s bien comme \u00e7a. Oui, parfois \u00e7a ne va pas, mais, en revanche, d\u2019autres fois \u00e7a va super bien! \u00a0Tu proposes quoi alors \u2013 la guillotine en tant qu\u2019un traitement des pellicules? <\/em><\/p>\n<p><em>Personne jamais ne peut \u00e9liminer ses \u00e9motions n\u00e9gatives, et si l\u2019on essaye on aura la totale de la part de la m\u00e8re nature. Ainsi est la Loi. Concernant la d\u00e9finition du but, vous n\u2019\u00eates pas all\u00e9s loin effectivement. <\/em><\/p>\n<p><em>Il n\u2019y a bien s\u00fbr aucun danger pour personne dans tout \u00e7a, si c\u2019est le sort de quelqu\u2019un de perdre la t\u00eate, il accomplira la t\u00e2che sans votre chemin tordu, quant aux exercices avec sa propre conscience \u2013 quelle diff\u00e9rence dans quel syst\u00e8me le faire \u2013 l\u2019individu soit s\u2019occupe de sa personne, soit non. Et si c\u2019est le cas, c\u2019est clair qu\u2019il est lui-m\u00eame responsable de lui. <\/em><\/p>\n<p><em>R\u00e9sum\u00e9:<\/em><\/p>\n<ol>\n<li><em>Le but mal formul\u00e9 de toute la performance. Les recherches de la v\u00e9rit\u00e9 excitent peu de gens, \u00e0 mon avis, bien que \u00e7a sonne tellement myst\u00e9rieux.<\/em><\/li>\n<li><em>Comment peut-on lutter contre les concepts qui emp\u00eachent de vivre si la notion m\u00eame du concept est cent fois exclue conceptuellement? <\/em><\/li>\n<li><em>En r\u00e9alit\u00e9, les \u00e9motions n\u00e9gatives ne s\u2019effacent pas chez vous, mais sont tu\u00e9es, c\u2019est-\u00e0-dire qu\u2019elles sont utilis\u00e9es comme une roue \u2013 une sorte de moteur perp\u00e9tuel. A droite je les supprime de toutes mes forces \u2013 \u00e7a y est, toutes sont tu\u00e9es, tout \u00e7a d\u00e9gringole quelque part en bas, se retourne par l\u00e0, et ressort \u00e0 gauche pour cogner la t\u00eate histoire de fou \u2013 \u00e7a donne une super sensation et le rapport de cons\u00e9quence est \u00e9tabli \u2013 l\u2019\u00e9motion est tu\u00e9e \u2013 tu l\u2019as v\u00e9cue. Une exp\u00e9rience! <\/em><\/li>\n<li><em>Donc, en r\u00e9alit\u00e9, les \u00e9motions sont soigneusement conserv\u00e9es et chouchout\u00e9es. <\/em><\/li>\n<\/ol>\n<p><em>Mais l\u2019admettre \u2013 se priver de la source \u00e9nerg\u00e9tique connue. <\/em><\/p>\n<p><em>Bien, ma ch\u00e8re. Toutes ses th\u00e9ories d\u00e9lirantes, sorties de nulle part, ne valent pas un clou, crois-moi, j\u2019ai \u00e9tudi\u00e9 tout \u00e7a. Tu penses quoi \u2013 les philosophes, les psychologues, et toute cette arm\u00e9e des scientifiques contemporains n\u2019y comprend rien en \u00e9motions, et toi tu as trouv\u00e9 par l\u00e0 un aigle qui sait tout? \u00a0Regarde le yoga! \u00a0Il n\u2019 y a pas un mot sur le fait qu\u2019il faut tuer\u00a0les \u00e9motions n\u00e9gatives! \u00a0Donc, ton yogi est bidon, rentre \u00e0 la maison, avant d\u2019y perdre compl\u00e8tement la t\u00eate.\u00bb <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Et voil\u00e0. Apr\u00e8s tout \u00e7a, pas un mot, ni m\u00eame \u00e9motions n\u00e9gatives. J\u2019ai tout simplement supprim\u00e9 les lettres, ferm\u00e9 ma boite et suis partie prendre du th\u00e9. Voil\u00e0, j\u2019ai touch\u00e9 \u00e0 la r\u00e9alit\u00e9. C\u2019est comme \u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<p>On peut fl\u00e2ner sur le Main Bazar jusqu\u2019\u00e0 en avoir le tournis, en passant par de petites boutiques pour rep\u00e9rer d\u2019innombrables bracelets, t-shirts, plaids, bric-\u00e0-brac, souvenirs, de l\u2019encens\u2026 quel con a invent\u00e9 le mot \u00abencens\u00bb? \u00a0Il y a tellement de trucs ici, que m\u00eame n\u2019ayant pas de but sp\u00e9cial d\u2019acheter quelque chose, apr\u00e8s une heure de fl\u00e2nerie dans des magasins on se retrouve un sac avec des achats entre les mains. En me distrayant de telle mani\u00e8re, j\u2019essayais de faire dispara\u00eetre, tuer les souvenirs de ceux que je consid\u00e9rais comme mes copains, quoi que\u2026 pourquoi? \u00a0Que mes souvenirs restent, c\u2019est quand m\u00eame mon exp\u00e9rience. A chaque fois que j\u2019avais un choc ou une crise, j\u2019essayais de l\u2019\u00e9vincer de ma conscience, l\u2019oublier, masquer, pl\u00e2trer, mais maintenant je crois que c\u2019est un faux acte, cela fait na\u00eetre certaines inqui\u00e9tudes de fond, qui restent suspendues en une l\u00e9g\u00e8re fum\u00e9e, allum\u00e9es comme une petite torche \u00e0 l\u2019arri\u00e8re plan de la conscience. Les inqui\u00e9tudes de fond\u2026 euh\u2026 quelque chose m\u2019a piqu\u00e9 au vif, j\u2019ai compris quelque chose\u2026 encore cette sensation surprenante \u2013 je viens de comprendre quelque chose, comment l\u2019exprimer en parole maintenant, comment le transformer en mots? \u00a0Ce n\u2019est pas la m\u00eame situation que j\u2019avais \u00e0 Bodh-gay\u00e2, puisque l\u00e0 je savais exactement ce que je comprenais, maintenant comme si cette compr\u00e9hension a apparu \u00e0 un niveau encore plus profond! \u00a0Maintenant je sais seulement qu\u2019une compr\u00e9hension est n\u00e9e en moi, mais je ne sais m\u00eame pas &#8211; ce que c\u2019est! \u00a0Quoi faire\u2026 \u00abCe que tu veux\u00bb. Etait-ce ma pens\u00e9e? \u00a0C\u2019\u00e9tait ma pens\u00e9e. Ou bien \u00e9tait-ce une voix dans ma t\u00eate? \u00a0D\u00e9finitivement\u2026 il y a vraiment une diff\u00e9rence entre de diff\u00e9rentes pens\u00e9es \u00e0 haute voix. Jamais auparavant je n\u2019ai essay\u00e9 de d\u00e9finir, exprimer, fixer cette diff\u00e9rence, n\u00e9anmoins elle existe. De diff\u00e9rentes pens\u00e9es ont \u2026 une qualit\u00e9 diff\u00e9rente, dirais-je, un go\u00fbt diff\u00e9rent. Mais maintenant peu importe, je vais laisser \u00e7a pour plus tard, ce qui importe c\u2019est que cette pens\u00e9e \u00e0 haute voix m\u2019a donn\u00e9 une id\u00e9e tr\u00e8s ing\u00e9nieuse \u2013 quoi faire d\u2019autre si ce n\u2019est pas faire ce que je veux? \u00a0Existe-il un indice plus s\u00fbr? \u00a0Et maintenant je veux me figer\u2026 mais comment le ferais-je ici \u2013 au milieu du magasin? \u00a0Je m\u2019en fous. Je m\u2019assois justement sur le bordure, je m\u2019en fiche \u2013 si l\u2019on me regarde ou pas \u2013 je m\u2019en fous. Je suis en train de me convaincre ou \u00e9liminer l\u2019inqui\u00e9tude? \u00a0Les deux\u2026 c\u2019est le r\u00e9sultat qui compte \u00e0 pr\u00e9sent. A pr\u00e9sent je veux r\u00e9p\u00e9ter encore et encore l\u2019expression \u00ables inqui\u00e9tudes de fond\u00bb. A haute voix! \u00a0C\u2019est bien que c\u2019est toujours bruyant ici\u2026 \u00abLes inqui\u00e9tudes de fond\u00bb\u2026 je l\u2019ai prononc\u00e9, je me suis fig\u00e9e, la pens\u00e9e a eu lieu et a fil\u00e9, en soulevant une poussi\u00e8re l\u00e9g\u00e8re dans le cerveau. \u00abLes inqui\u00e9tudes de fond\u00bb\u2026 Encore une fois\u2026 m\u2019accorder, pr\u00eater l\u2019oreille\u2026 Sart\u2026 et pourquoi Sart? &#8230; le pr\u00e9nom de Sart a \u00e9merg\u00e9, bien\u2026 les inqui\u00e9tudes de fond\u2026 Sart\u00a0\u2026 Oh! &#8230; Ca ne m\u2019inqui\u00e8te plus qui va penser quoi de moi. J\u2019ai compris que j\u2019ai compris!! Les inqui\u00e9tudes de fond \u2013 le fond n\u00e9gatif. Au moment o\u00f9 ces deux expressions se sont form\u00e9es, tout a pris sa place. Une certitude en b\u00e9ton est survenue de quelque part comme quoi ce que j\u2019avais appel\u00e9 les inqui\u00e9tudes de fond \u00e9tait justement ce que dans la pratique de la voir directe est appel\u00e9 le fond n\u00e9gatif. Il est absolument \u00e9vident que le fond n\u00e9gatif est les m\u00eames \u00e9motions n\u00e9gatives, c\u2019est juste qu\u2019elles sont \u00ab\u00e9tal\u00e9es\u00bb, enfonc\u00e9es profond\u00e9ment, et se repr\u00e9sentent en une couche de fond des \u00e9motions n\u00e9gatives. Elles n\u2019ont pas d\u2019\u00e9clats prononc\u00e9s, et lorsqu\u2019un tel \u00e9clat appara\u00eet, je n\u2019y vois qu\u2019une simple \u00e9motion n\u00e9gative, souvent en ne me rendant pas compte qu\u2019elle n\u2019a pas apparu de nulle part, qu\u2019elle a une couche nourrici\u00e8re sous forme du fond n\u00e9gatif. Le fond n\u00e9gatif\u2026 et oui\u2026 cette saloperie, comme je la vois, est tr\u00e8s \u00e9tendue dans le temps, elle peut durer des heures, des jours, des mois, toute la vie\u2026 toute la vie\u2026 Je ne suis presque jamais sortie du fond n\u00e9gatif ininterrompu! \u00a0Justement cette fuite des souvenirs douloureux, comme \u00e7a peut para\u00eetre \u00e9trange, le nourrit, l\u2019accro\u00eet. Non, dans tous les cas, ind\u00e9pendamment de l\u2019exactitude ou de fausset\u00e9 de ces raisonnements, d\u00e9finitivement je ne veux pas \u00e9viter mon exp\u00e9rience, je veux voir le monde tel qu\u2019il est pour moi, et si quelque chose provoque des sentiments douloureux\u2026 c\u2019est quoi \u00e7a \u2013 \u00ables sentiments douloureux\u00bb, ils acqui\u00e8rent tout de suite un autre statut, ce n\u2019est plus de la merde, coll\u00e9 sur la route, ce sont d\u00e9j\u00e0 \u00abdes sentiments\u00bb. Ca me rappelle l\u2019histoire de la migraine qui \u00e9tait consid\u00e9r\u00e9e auparavant comme une maladie des aristocrates et per\u00e7ue \u00e0 cause de \u00e7a non comme une maladie mais comme un signe des origines nobles.<\/p>\n<p>Apr\u00e8s avoir fait cette d\u00e9couverte et chang\u00e9 la vision des souvenirs n\u00e9gatifs, la perception de la vie courante n\u2019a pas manqu\u00e9 de changer \u2013 m\u00eame le ciel est devenu plus clair. J\u2019ai eu de nouveau le d\u00e9sir de retourner dans le cyber caf\u00e9 pour continuer \u00e0 lire mon courrier \u2013 il y avait un tas de messages.<\/p>\n<p>Natashka. Ben\u2026 j\u2019ai peur d\u2019ouvrir son message \u2013 qui sait ce qu\u2019il contient! ? Quand m\u00eame Natashka ne vient pas du pass\u00e9 aussi lointain, je la per\u00e7ois de mani\u00e8re plus ad\u00e9quate. Et bah\u2026 j\u2019appelle le pass\u00e9 lointain ce qui ce passait il y a deux mois\u2026 est-ce possible \u2013 changer AINSI en deux mois\u2026 Il n\u2019y a plus d\u2019ancienne Maya, plus du tout, il y a tout \u00e0 fait une autre cr\u00e9ature \u00e0 sa place maintenant. D\u2019ailleurs, je n\u2019ai pas r\u00e9pondu \u00e0 son message concernant Daramsala.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00abSalut, Mayka! \u00a0Il a neig\u00e9 de mani\u00e8re toute \u00e0 fait inattendue chez nous, le froid est arriv\u00e9, tout le monde se couvre de fringues chaudes, il ne me reste que me rappeler avec sourire comment j\u2019essayais de fuir la chaleur indienne. <\/em><\/p>\n<p><em>Je suis rentr\u00e9e chez moi \u00e0 Moscou. Au d\u00e9but tout \u00e9tait horrible, la vie m\u2019a immerg\u00e9e vite et sans que je m\u2019en aper\u00e7oive dans son marais. Tout \u00abs\u2019est arrang\u00e9\u00bb, car j\u2019ai d\u00fb comprendre mes certains m\u00e9contentements, le calme est survenu, l\u2019int\u00e9r\u00eat envers certaines choses a r\u00e9apparu. Il me semblait que je faisais tout comme il fallait, que je luttais contre les EN, je changeais ma vision du monde, j\u2019agissais conform\u00e9ment \u00e0 mes d\u00e9sirs, mais bient\u00f4t je me suis rendue compte que je m\u2019\u00e9tais arr\u00eat\u00e9e. J\u2019ai cess\u00e9 d\u2019\u00e9crire et analyser, je l\u2019ai remplac\u00e9 par la lecture. Les situations provoquant des souffrances ont disparu. Tout parait normal, je ne ressens pas la lourdeur douloureuse du d\u00e9sespoir. Apr\u00e8s un mois entier c\u2019est tout ce que j\u2019ai pu dire de ma vie! \u00a0Quelle horreur. Lorsque j\u2019ai vu tout \u00e7a, que je m\u2019immergeais promptement dans le marais, que je mourrais, quelque chose a sembl\u00e9 se lib\u00e9rer en moi, une sorte d\u2019essor, et je me suis mise \u00e0 me battre. <\/em><\/p>\n<p><em>Ce dernier temps je fais des r\u00eaves tr\u00e8s vifs, souvent je suis consciente de tout ce qui se passe dans le r\u00eave, je fais certaines conclusions pour moi. Les situations et conversations qui se d\u00e9roulent dans les r\u00eaves sont proches \u00e0 certain point \u00e0 mes inqui\u00e9tudes actuelles. Je fais des d\u00e9couvertes dans mes r\u00eaves et ensuite je me r\u00e9veille pour reconstituer le r\u00eave dans ma conscience. Puis je me rendors, en souhaitant de me replonger dans l\u2019ancien r\u00eave, mais d\u2019autres \u00e9v\u00e8nements surviennent, pas moins vifs, tr\u00e8s vifs, color\u00e9s. <\/em><\/p>\n<p><em>Dans le r\u00eave je sens que des sentiments extraordinaires me saisissent. Le lendemain matin je ne parviens pas \u00e0 reconstituer mes r\u00eaves aussi distinctement, mais certaines images se conservent. En g\u00e9n\u00e9ral, je me souviens de mes r\u00eaves, les couleurs se reconstituent, ainsi que certaines perceptions. Qu\u2019en penses-tu, c\u2019est quoi les r\u00eaves? \u00a0Qu\u2019est-ce que\u00a0les gens ressentent en dormant, qu\u2019est-ce qui leur arrive? Est-ce tout le temps qu\u2019on fait des r\u00eaves, en les oubliant le matin? \u00a0<\/em><\/p>\n<p><em>L\u2019ann\u00e9e prochaine je veux retourner \u00e0 Daramsala, je veux aller au N\u00e9pal, dans les montagnes. Peut-\u00eatre ira-t-on ensemble, ah? \u00a0Je le voudrais tellement\u2026 <\/em><\/p>\n<p><em>Les parents m\u2019influencent beaucoup, l\u2019ambiance m\u00eame \u00e0 la maison me rend incessamment inqui\u00e8te et m\u2019agace, parfois je craque et je le regrette plus tard. J\u2019ai pris la d\u00e9cision de partir, mais ne serait-ce la fuite? \u00a0Peut-\u00eatre il vaut mieux que je reste, et juste dans ce bouilli j\u2019essaye de continuer \u00e0 \u00e9liminer les \u00e9motions n\u00e9gatives? \u00a0Je suis retourn\u00e9e \u00e0 cette id\u00e9e \u00e0 toi, parce que j\u2019ai compris que je ne pouvais pas vivre autrement, sinon ces viles cr\u00e9atures me boufferont. J\u2019y suis retourn\u00e9e de nouvelle mani\u00e8re, sans enthousiasme ardent, sans consid\u00e9rer cette occupation comme une sorte de procuration des impressions. Maintenant tout est autrement, maintenant l\u00e0 est mon espoir.<\/em><\/p>\n<p><em>Sinon il y a quelque chose que je voulais te dire mais je suis g\u00ean\u00e9e. L\u00e0 je pense \u2013 \u00abje vais arriver \u00e0 dire\u00bb et tout de suite \u2013 la honte, la stupeur, les doutes\u2026 Mais quand je pense que je ne te le dirai jamais je ne sais pas alors \u2013 \u00e0 quoi bon vivre? \u00a0Pourquoi vire si le plus merveilleux tombe dans le pi\u00e8ge de la honte? \u00a0Sinon quoi attendre de la vie? \u00a0N\u2019est-ce pas une trahison \u2013\u00a0marcher ainsi sur soi-m\u00eame? Toi tu ne comprends peut-\u00eatre pas de quoi je parle\u2026 Je vais m\u2019y d\u00e9cider, Mayka, je vais l\u2019\u00e9crire tout de suite. Mayka, je t\u2019aime. Voil\u00e0. Je suis amoureuse de toi, j\u2019ai envie de toi, dans mes r\u00eaves je te fais souvent l\u2019amour, dans ces r\u00eaves tu es toujours une fille, mais en m\u00eame temps tu es un gar\u00e7on aussi, tu comprends? \u00a0Honn\u00eatement, je n\u2019ai aucune exp\u00e9rience de faire l\u2019amour avec des filles, je n\u2019ai jamais pens\u00e9 que je pourrais tout \u00e0 coup tomber amoureuse d\u2019une fille\u2026 et je me sens tr\u00e8s g\u00ean\u00e9e par ce que je ressens \u00e0 ton \u00e9gard. Tu te souviens, quand on se prenait dans les bras de fa\u00e7on tellement amicale, innocemment, dans ces moments l\u00e0 comme si tout s\u2019enflammait en bas de mon ventre\u2026 je voulais te l\u2019avouer alors, mais je n\u2019ai pas eu le courage. Tu m\u2019aideras \u00e0 le surmonter, Mayka? \u00a0Je le veux tellement. Dis-moi ce que tu en penses? \u00a0Juste sois franche, d\u2019accord? \u00a0<\/em><\/p>\n<p><em>Ta Natashka.\u00bb <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Ma poup\u00e9e c\u00e2line\u2026 En me rejetant sur le dossier de la chaise, je ressentais une telle tendresse\u2026 si je rentre \u00e0 Moscou, tu auras de mes nouvelles, ma petite chatte passionn\u00e9e. Le d\u00e9sir de r\u00e9pondre a apparu tout de suite, et, sans le reporter, je me suis adonn\u00e9e \u00e0 la r\u00e9ponse.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00abMa petite Natashka\u2026 Bien s\u00fbr, je ne pourrais pas r\u00e9soudre tes probl\u00e8mes, li\u00e9s \u00e0 la recherche du sens et \u00e0 la d\u00e9livrance des \u00e9motions n\u00e9gatives, \u00e0 ta place, je ne sais pas ce qui est mieux \u2013 quitter les parents ou rester, il faut plut\u00f4t suivre ses d\u00e9sirs. Ma raison me dit que dans une situation o\u00f9 il y a trop d\u2019\u00e9motions n\u00e9gatives, tu pourras tout simplement ne pas arriver \u00e0 en venir au bout. Et si d\u2019abord apprendre \u00e0 les combattre dans des situations plut\u00f4t confortables, ensuite il est possible de transf\u00e9rer ses entra\u00eenements dans des conditions plus dures. Mais ce n\u2019est que des raisonnements, comment faire dans une situation donn\u00e9e- c\u2019est \u00e0 toi de d\u00e9cider. Personne ne peut porter la responsabilit\u00e9 de tes d\u00e9cisions \u00e0 ta place. Mais, en tout cas, je peux essayer de r\u00e9pondre \u00e0 tes questions quand tu les poses, et je pense que quand je rentrerai \u00e0 Moscou, je pourrai te serrer contre moi fort et tendrement, en regardant dans tes yeux ou te parlant, ou bien embrasser tes l\u00e8vres voluptueuses, et le fait que tu te bats avec toi-m\u00eame avec les r\u00e9sultats variables ne change rien dans ce que je ressens \u00e0 ton \u00e9gard. <\/em><\/p>\n<p><em>Ma Natashka timide\u2026 Tu es g\u00ean\u00e9e aussi de m\u2019\u00e9crire que tu as envie de moi? \u00a0J\u2019aime \u00e7a aussi en toi. Et \u00e7a aussi. J\u2019aime te parler et nous imaginer ensemble\u2026 imaginons ensemble \u2013 comment \u00e7a se passera, hein? \u00a0Je veux \u00eatre gar\u00e7on et fille avec toi en m\u00eame temps, et tu sais ce qu\u2019on fera? \u00a0Je m\u2019ach\u00e8terai un godemich\u00e9 classe qui s\u2019attache, un peu courb\u00e9, \u00e9lastique, tout \u00e0 fait comme un vrai, d\u2019abord je te ferai des c\u00e2lins, comme une fille, ensuite je te prendrai comme un gar\u00e7on, et lorsqu\u2019au bout de quelques heures de c\u00e2lins, frisant l\u2019orgasme, tu d\u00e9cideras de franchir cette limite, tu diras\u00bb\u00e7a y est, je ne peux plus me retenir, je ne veux plus m\u2019arr\u00eater, ne t\u2019arr\u00eate plus\u2026\u00bb, moi je dirai \u00abnon, ma petite, dis-moi que tu VEUX JOUIR\u00bb, je t\u2019embrasserai dans la bouche, je mordillerai ta petite langue douce et tendre, tu ne pourras pas bien s\u00fbr me refuser, et, en surmontant ta timidit\u00e9 tu diras &#8211; \u00aboui, je veux jouir maintenant, je veux tellement jouir maintenant et avec toi, Mayka\u00bb\u2026 tu me serreras tr\u00e8s fort, tu fermeras tes yeux, et moi je couvrirai tes joues, tes l\u00e8vres, tes yeux, ton menton, tes petites oreilles, tes seins de baisers\u2026 en bougeant dans toi, en te rapprochant lentement de la limite\u2026 ensuite je te baiserai plus fort, plus puissamment, en te p\u00e9n\u00e9trant plus profond \u2013 aussi profond\u00e9ment que possible, et vague par vague le plaisir du sexe et de la tendresse d\u00e9ferlera sur toi, le feu en bas de ton petit ventre va se m\u00ealer avec le plaisir de recevoir mes baisers et mes c\u00e2lins sur ton cou, et lorsque tu te mettras te pelotonner en t\u2019ouvrant \u00e0 l\u2019orgasme d\u00e9ferlant, je serrerai fort tes seins, tes petits mamelons, en t\u2019entrant puissamment \u00e0 chaque fois, en allumant la flemme qui t\u2019as envahie toute enti\u00e8re\u2026 je saisirai tes grognements, tes cris et ta respiration avec mes l\u00e8vres\u2026 je l\u00e8cherai tes petites larmes\u2026 ma petite Natashka\u2026 <\/em><\/p>\n<p><em>Si tu veux vaincre ta timidit\u00e9, je t\u2019aiderai bien s\u00fbr, mais \u00e7a ne veut pas dire que j\u2019ai un projet quelconque concernant tes changements. Je souhaite que les gens bougent dans la direction qu\u2019ILS veulent EUX, et si tu veux devenir mod\u00e9r\u00e9ment libertine, et n\u00e9anmoins rester timide dans une certaine mesure, c\u2019est super\u2026 puisque ce qui excite et attire et provoque la tendresse ce n\u2019est pas une forme d\u00e9finie quelconque, dans laquelle tu exprimes ta passion et ta tendresse, mais cette m\u00eame passion et tendresse elles-m\u00eames, ce que tu ressens, quelle diff\u00e9rence alors \u2013 si tu seras timide ou libertine avec moi? \u00a0Dans tous les cas, cela \u00e9veillera en moi les sensations r\u00e9ciproques. J\u2019arrive facilement \u00e0 imaginer qu\u2019on peut \u00eatre tr\u00e8s d\u00e9velopp\u00e9e et d\u00e9sinhib\u00e9e sexuellement et faire du\u00a0libertinage \u00able plus d\u00e9prav\u00e9\u00bb en restant en m\u00eame temps timide comme une pucelle, d\u00e9licate\u2026 je t\u2019imagine facilement comme \u00e7a, et j\u2019aime cette image de toi. <\/em><\/p>\n<p><em>Si tu veux commencer \u00e0 avancer dans le sens d\u2019\u00e9panouissement sexuel, je peux te conseiller d\u2019abord de te rendre clairement compte de ce que tu veux avoir exactement dans le sexe. Les notions de ce qui est admissibles ou pas bloquent l\u2019imagination elle-m\u00eame, et au cas o\u00f9 l\u2019imagination est supprim\u00e9e, dans la r\u00e9alit\u00e9 il est tr\u00e8s difficile de se comporter librement. Je te propose de faire une liste de tes fantaisies sexuelles. Le mieux c\u2019est de le faire en te masturbant, quand tu t\u2019approches de l\u2019orgasme en restant quelques temps sur la limite \u2013 laisse ta fantaisie libre, laisse-la se d\u00e9sinhiber, \u00eatre voluptueuse. Invente une sc\u00e8ne, un sujet, une id\u00e9e qui t\u2019exciteraient particuli\u00e8rement. Ne manque pas de la noter, ne jette pas cette note juste parce que la disposition sexuelle est pass\u00e9e et les interdictions morales sont entr\u00e9es en force. Fais la liste de telles fantaisies et tu verras ta vision du monde se transformer \u2013 pas seulement dans le domaine sexuel. Fais de sorte que personne ne puisse lire tes notes \u2013 si tu les fais sur le papier, transmets-les dans un fichier, jette le papier, et s\u00e9curise l\u2019acc\u00e8s au fichier. Si tu as le doute que quelqu\u2019un puisse les lire, tu ne pourras pas \u00eatre sinc\u00e8re avec toi-m\u00eame. Tu peux y mettre aussi des sujets entiers sur une aventure sexuelle quelconque, ainsi que des scetches et fragments. <\/em><\/p>\n<p><em>Bon, mon museau, ne t\u2019endors pas par l\u00e0, ne c\u00e8de pas \u00e0 ce hymne ber\u00e7ant, de cimeti\u00e8re, chant\u00e9 par le ch\u0153ur de ton entourage\u00bb. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>La nuit suivante je me retrouve au restaurant \u00abAdjay\u00bb. Chicken sizzler, je voudrais\u2026 oui, on le pr\u00e9pare bien ici. Je me suis trouv\u00e9e une occupation int\u00e9ressante\u2026 la journ\u00e9e de la marmotte en langue d\u00e9lhienne \u2013 je rencontre du monde, j\u2019en trie ceux qui ont l\u2019air plus ou moins intelligents \u2013 des scientifiques, des \u00e9crivains, je leur parle en abordant le sujet des \u00e9motions n\u00e9gatives et de leur \u00e9limination. Je leur explique tout, je r\u00e9ponds \u00e0 leur questions et objections, ensuite on se s\u00e9pare, demain il y aura d\u2019autres gens, demain je vais tout expliquer de nouveau. Leurs r\u00e9actions sont pareilles en g\u00e9n\u00e9ral \u2013 impuissamment int\u00e9ress\u00e9es, \u00e7a se voit que les gens recherchent des impressions et ils per\u00e7oivent le sujet des \u00e9motions n\u00e9gatives et des perceptions de mani\u00e8re dont je per\u00e7ois le r\u00e9cit de cette personne devant moi au sujet des grenouilles. Pour lui une grenouille &#8211; c\u2019est sa vie, son travail, et notre conversation est un troc. Je vais faire style que tes grenouilles m\u2019int\u00e9ressent, et toi tu feras comme si mes \u00e9motions n\u00e9gatives t\u2019int\u00e9ressaient. Ainsi on communique.<\/p>\n<p>-\u2026 c\u2019est justement dans les montagnes \u00e0 l\u2019ouest de l\u2019Inde qu\u2019on a trouv\u00e9 ce qui paraissait introuvable \u2013 l\u2019esp\u00e8ce perdue autrefois des grenouilles pourpres. C\u2019est incroyable, car elles ont saut\u00e9 sous les pieds des dinosaures \u2013 de belles grenouilles pourpres ayant une petite t\u00eate. Avant on croyais que cette esp\u00e8ce de grenouille soit \u00e9tait morte depuis longtemps, soit n\u2019existait jamais\u2026<\/p>\n<p>C\u2019est curieux \u2013 de quoi il parle avec sa femme? \u00a0Avec ses amis? \u00a0Toutes ces conversations m\u2019aident \u00e0 comprendre que les gens prennent l\u2019id\u00e9e de l\u2019\u00e9limination des \u00e9motions n\u00e9gatives pour quelque chose comme la recherche des grenouilles pourpres \u2013 comme quelque chose qui peut procurer des impressions, de diversifier un peu la vie, ou m\u00eame ajouter une nouvelle page dans les livres de psychologie. Ils ne per\u00e7oivent pas cette id\u00e9e comme quelque chose qui puisse changer leur vie en profondeur\u2026<\/p>\n<p>-\u2026 ce n\u2019est pas simplement une nouvelle esp\u00e8ce. Nous avons d\u00e9couvert une nouvelle branche de l\u2019\u00e9volution! \u00a0La d\u00e9couverte de cette esp\u00e8ce nous aidera \u00e0 comprendre de quelle mani\u00e8re les grenouilles ont \u00e9volu\u00e9, sans cette d\u00e9couverte leur \u00e9volution serait rest\u00e9e un \u00e9nigme pour toujours, puisqu\u2019il n\u2019y a aucun donn\u00e9e arch\u00e9ologique, aucun fossile datant de cette \u00e9poque. Les montagnes de Gh\u00e2ts sont un tr\u00e9sor, et le temps qu\u2019il existe sous son aspect originel, il faut les pr\u00e9server et examiner.<\/p>\n<p>&#8211; Dis-moi, Frankie, comment tout \u00e7a changera ta vie?<\/p>\n<p>Pourquoi est-ce que j\u2019ai pos\u00e9 cette question? \u00a0Il ne comprend pas qu\u2019il ne s\u2019agit pas d\u2019une prime, ni d\u2019une chaire\u2026 il ne voit pas. Ok, Frankie, je te souhaite bonne chance dans tes recherches des papillons\u2026 non, c\u2019est-\u00e0-dire des grenouilles, ouf\u2026<\/p>\n<p>A une table \u00e0 c\u00f4t\u00e9 \u2013 une jeune fille mignonne, une petite japonaise\u2026 Un petit corps soign\u00e9, toute petite, un peu marrante. Les genoux serr\u00e9s l\u2019un contre l\u2019autre, elle mange proprement, concentr\u00e9e. En l\u2019observant j\u2019ai ressenti tout \u00e0 coup un \u00e9clat inattendu de l\u2019attirance \u00e9rotique. Ce n\u2019est m\u00eame pas l\u2019envie de lui faire l\u2019amour, c\u2019est plut\u00f4t l\u2019envie de la regarder tout simplement, de la caresser peut-\u00eatre, embrasser, mais comment y parvenir\u2026 on a \u00e9chang\u00e9 deux phrases polies \u2013 elle est tr\u00e8s souriante, sociable, mais derri\u00e8re tout \u00e7a\u2026 il manque quelque chose, quelque chose ne va pas. Peu importe \u2013 je vais essayer quand m\u00eame et je verrai.<\/p>\n<p>&#8211; Tu veux que je t\u2019apprenne un peu le russe?<\/p>\n<p>Elle veut bien. Viens chez moi? \u00a0J\u2019habite ici \u00e0 c\u00f4t\u00e9. Elle dessine des hi\u00e9roglyphes, \u00e7a lui r\u00e9ussit, en s\u2019\u00e9tendant sur mon lit, elle me montre \u2013 comment mener le feutre pour qu\u2019un hi\u00e9roglyphe soit particuli\u00e8rement gracieux\u2026 elle a dessin\u00e9 le mot \u00abMaya\u00bb en japonais. Oui, c\u2019est tr\u00e8s beau, merci\u2026 \u00e9coute, ma petite, viens on se prend en photo? \u00a0Elle ne refuse pas. Est-ce que je peux faire une photo \u00absp\u00e9ciale\u00bb? \u00a0Elle ne comprend pas \u2013 \u00e7a veut dire quoi \u00absp\u00e9ciale\u00bb? \u00a0Oui, tu peux\u2026 je lui donne l\u2019appareil photo, je la pose contre le mur \u2013 quand je te dirai, tu prendras la photo, d\u2019accord? \u00a0Je prends son petit pied, habill\u00e9 en une chaussette marrante, comme pour les petites filles, en fleurs, je le serre contre mes l\u00e8vres, je l\u2019embrasse \u2013 prends la photo! \u00a0La fille est en choc, mais elle prend la photo. J\u2019enl\u00e8ve la chaussette\u2026 quel petit pied, il est bon\u2026 je pousse ma langue entre ses petits orteils, je \u00abbaise\u00bb son pied, je l\u00e8che la petite plante douce, je prends les orteils dans la bouche en les su\u00e7ant, je couvre le talon des baisers\u2026 Ca te plait? \u00a0Non??!!<\/p>\n<p>&#8211; Je laisse son pied, je l\u2019approche en quatre pattes. Tu n\u2019aimes pas??<\/p>\n<p>&#8211; Non\u2026- elle sourit doucement, poliment.<\/p>\n<p>&#8211; C\u2019est pas possible\u2026 comment, c\u2019est d\u00e9sagr\u00e9able?<\/p>\n<p>&#8211; Si\u2026 mais il ne faut pas.<\/p>\n<p>&#8211; D\u2019accord\u2026<\/p>\n<p>Elle enl\u00e8ve son pied, met la chaussette, elle se sent g\u00ean\u00e9e, me regarde sans savoir quoi dire.<\/p>\n<p>&#8211; Je peux te toucher la main?<\/p>\n<p>&#8211; Bien s\u00fbr, la main tu peux, &#8211; elle me tend sa paume, soulag\u00e9e.<\/p>\n<p>Je la prends pour la caresser, embrasser les petits doigts, je pousse ma langue encore entre ses doigts, je l\u00e8che sa paume, en couvrant le poignet de baisers, en remontant jusqu\u2019au l\u2019endroit tendre du repli du coude, quelle peau tendre\u2026 je la mordille\u2026 tu aimes? \u00a0Non??!!<\/p>\n<p>&#8211; Non\u2026<\/p>\n<p>Ce n\u2019est pas possible, je le sens pourtant? \u00a0Elle doit avoir toute sa chatte mouill\u00e9e!<\/p>\n<p>C\u2019est quoi que tu n\u2019aimes pas, ma petite?<\/p>\n<p>&#8211; Voil\u00e0, regarde, &#8211; elle enl\u00e8ve un m\u00e9daillon de sa poitrine, elle l\u2019ouvre pour me montrer. Il y a une photo d\u2019un gar\u00e7on japonais.<\/p>\n<p>&#8211; C\u2019est ton mari?<\/p>\n<p>&#8211; Fianc\u00e9\u2026<\/p>\n<p>&#8211; C\u2019est pour \u00e7a \u2013 tu ne veux pas faire l\u2019amour avec moi parce qu\u2019il sera jaloux?<\/p>\n<p>&#8211; Non, je ne peux pas comme \u00e7a, il est mon fianc\u00e9.<\/p>\n<p>&#8211; Mais tu as aim\u00e9?<\/p>\n<p>&#8211; Oui, j\u2019ai aim\u00e9\u2026<\/p>\n<p>&#8211; Beaucoup?<\/p>\n<p>&#8211; Oui.<\/p>\n<p>Je ne veux pas continuer \u00e0 s\u00e9duire ce petit chaton nippon. Elle me plait beaucoup, elle est tr\u00e8s tendre, des yeux doux, elle a un go\u00fbt si bon\u2026 mais je ne veux plus. Je comprends bien que si je continue \u00e0 la caresser, je parviendrai facilement \u00e0 la s\u00e9duire et faire tout ce que je veux, je la ferai jouir dix fois, mais quoi apr\u00e8s? \u00a0Apr\u00e8s elle souffrira de sa \u00abtrahison\u00bb, ne pourras plus regarder son gar\u00e7on dans les yeux aussi sinc\u00e8rement, je ne veux pas de \u00e7a.<\/p>\n<p>&#8211; Il ne comprendra pas?<\/p>\n<p>&#8211; Non, il ne comprendra pas, il m\u2019en voudra s\u2019il apprend, et moi je ne veux pas mentir, je ne peux pas mentir \u00e0 mon fianc\u00e9. Je ne peux pas, il ne faut pas\u2026<\/p>\n<p>Je la serre contre moi pour la rassurer \u2013 mais non, ma petite, je ne ferai rien bien s\u00fbr contre ton envie, je ne veux pas tenter de te convaincre, je comprends que c\u2019est ta d\u00e9cision, ce sera comme tu as d\u00e9cid\u00e9, tu me plait comme \u00e7a\u2026 laisse-moi te prendre dans mes bras encore une fois et prenons-nous en photo tout simplement pour le souvenir, enlac\u00e9es, comme des copines, d\u2019accord? \u00a0Son visage s\u2019\u00e9claire d\u2019un sourire \u2013 \u00aboui, bien s\u00fbr\u00bb! \u00a0On pose l\u2019appareil photo sur une chaise, je prends la t\u00e9l\u00e9commande et je serre la fille contre moi. Tiens \u2013 quand on se prend dans les bras comme des \u00abcopines\u00bb, l\u00e0 elle est comme une vraie tigresse passionn\u00e9e\u2026 Je peux te faire un bisou? \u00a0Juste une fois \u2013 comme une copine embrasse une copine? \u00a0Je peux?! \u00a0Hourra! \u00a0Je touche tendrement sa joue, son petit nez et ses l\u00e8vres avec mes l\u00e8vres\u2026 ah, quelles l\u00e8vres\u2026 encore et encore\u2026 c\u2019est quoi \u00e7a \u2013 elle a sorti sa petite langue! \u00a0Bah, la petite pute! \u00a0J\u2019ai l\u00e9ch\u00e9 sa langue un coup, elle a tout de suite disparu\u2026 mais elle en veut\u2026 je le sens \u2013 comment elle en veut, \u00e0 quel point profond\u00e9ment mes baisers retentissent en elle\u2026 est-ce possible \u2013 \u00e9craser sa sexualit\u00e9 de telle mani\u00e8re\u2026 de nouveau l\u2019inqui\u00e9tude grandit en elle \u2013 notre baiser \u00abde copine\u00bb a cess\u00e9 depuis longtemps d\u2019\u00eatre un tel, je la laisse, je caresse son \u00e9paule, je la rassure de nouveau, en lui disant quelque chose d\u2019abstrait\u2026 j\u2019avais oubli\u00e9 qu\u2019il y a des filles tout \u00e0 fait ordinaires &#8211; complex\u00e9es jusqu\u2019\u00e0 l\u2019impossible. Sart, Ta\u00eega, Kam\u2026 &#8211; cela existait-il? \u00a0Quel pr\u00e9cipice gigantesque\u2026 Qu\u2019est-ce que je fais ici? &#8230; Je l\u2019accompagne jusqu\u2019\u00e0 la porte. Salut, ma petite, je t\u2019enverrai nos photos \u00e0 ton mail, ok? \u00a0Bien, \u00e9cris-moi quand tu veux, mon petit chaton japonais\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma derni\u00e8re p\u00eache \u00e0 l\u2019Internet \u2013 un message d\u2019un copain de longue date \u2013 il m\u2019a r\u00e9pondu promptement! \u00a0Super. Il doit rester au travail \u00e0 s\u2019ennuyer et \u00e0 lire son courrier. Il me manque m\u00eame un peu\u2026 Son avis est int\u00e9ressant \u2013 j\u2019ai toujours aim\u00e9 lui parl\u00e9, c\u2019est un gars qui a une bonne formation [&hellip;]<\/p>\n","protected":false},"author":8235,"featured_media":0,"parent":7693,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9608","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chapitre 39 - Selection of Attractive States<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chapitre 39 - Selection of Attractive States\" \/>\n<meta property=\"og:description\" content=\"Ma derni\u00e8re p\u00eache \u00e0 l\u2019Internet \u2013 un message d\u2019un copain de longue date \u2013 il m\u2019a r\u00e9pondu promptement! \u00a0Super. Il doit rester au travail \u00e0 s\u2019ennuyer et \u00e0 lire son courrier. Il me manque m\u00eame un peu\u2026 Son avis est int\u00e9ressant \u2013 j\u2019ai toujours aim\u00e9 lui parl\u00e9, c\u2019est un gars qui a une bonne formation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/\" \/>\n<meta property=\"og:site_name\" content=\"Selection of Attractive States\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"43 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-39\\\/\",\"url\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-39\\\/\",\"name\":\"Chapitre 39 - Selection of Attractive States\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/#website\"},\"datePublished\":\"2015-03-19T18:49:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-39\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-39\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-39\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMAYA\u00bb. Livre 1: Force mineure\",\"item\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chapitre 39\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/\",\"name\":\"Selection of Attractive States\",\"description\":\"Psychologie exp\u00e9rimentale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chapitre 39 - Selection of Attractive States","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/","og_locale":"fr_FR","og_type":"article","og_title":"Chapitre 39 - Selection of Attractive States","og_description":"Ma derni\u00e8re p\u00eache \u00e0 l\u2019Internet \u2013 un message d\u2019un copain de longue date \u2013 il m\u2019a r\u00e9pondu promptement! \u00a0Super. Il doit rester au travail \u00e0 s\u2019ennuyer et \u00e0 lire son courrier. Il me manque m\u00eame un peu\u2026 Son avis est int\u00e9ressant \u2013 j\u2019ai toujours aim\u00e9 lui parl\u00e9, c\u2019est un gars qui a une bonne formation [&hellip;]","og_url":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/","og_site_name":"Selection of Attractive States","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"43 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/","url":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/","name":"Chapitre 39 - Selection of Attractive States","isPartOf":{"@id":"https:\/\/bodhi.name\/ru\/#website"},"datePublished":"2015-03-19T18:49:59+00:00","breadcrumb":{"@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-39\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/bodhi.name\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00abMAYA\u00bb. Livre 1: Force mineure","item":"https:\/\/bodhi.name\/fr\/maya-livre-1\/"},{"@type":"ListItem","position":3,"name":"Chapitre 39"}]},{"@type":"WebSite","@id":"https:\/\/bodhi.name\/ru\/#website","url":"https:\/\/bodhi.name\/ru\/","name":"Selection of Attractive States","description":"Psychologie exp\u00e9rimentale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodhi.name\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/users\/8235"}],"replies":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/comments?post=9608"}],"version-history":[{"count":1,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9608\/revisions"}],"predecessor-version":[{"id":9609,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9608\/revisions\/9609"}],"up":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/7693"}],"wp:attachment":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/media?parent=9608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}