{"id":9563,"date":"2015-03-18T21:39:14","date_gmt":"2015-03-18T17:39:14","guid":{"rendered":"http:\/\/bodhi.name\/?page_id=9563"},"modified":"2015-03-18T21:39:14","modified_gmt":"2015-03-18T17:39:14","slug":"chapitre-27","status":"publish","type":"page","link":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/","title":{"rendered":"Chapitre 27"},"content":{"rendered":"<p>Dans aucun trou du cul du monde il ne pue autant qu\u2019en Inde. J\u2019ai toujours \u00e9t\u00e9 sensible aux odeurs comme un animal\u00a0d\u00e9licat. Le m\u00e9tro, des petits bus bond\u00e9s, des ascenseurs sont les endroits de mes tortures olfactives: ce mec a mang\u00e9 du fromage amer ce matin, et cette bonne femme l\u00e0 s\u2019est arros\u00e9e avec un flacon entier de parfum bon march\u00e9, le voisin \u00e0 droite a un estomac malade, apparemment, et \u00e0 gauche il y a un fumeur gris comme la bitume\u2026 Et des retrait\u00e9s naphtalineux! \u00a0Leur odeur qui m\u2019inspire d\u2019une horreur de tombeau. Est-ce possible que ma sensibilit\u00e9 olfactive se soit aiguis\u00e9e encore plus? \u00a0Ca m\u2019\u00e9tonnerait\u2026 mais quand m\u00eame ce n\u2019\u00e9tait pas comme \u00e7a avant. Peut-\u00eatre c\u2019est parce que avant je ne m\u2019\u00e9tais pas aventur\u00e9e hors des quartiers o\u00f9 des touristes se frayent, en me d\u00e9pla\u00e7ant d\u2019un endroit \u00e0 l\u2019autre dans des bus bouchonn\u00e9s. O\u00f9 alors sont des r\u00e9gions de l\u2019Himalaya plus propres que la partie continentale de l\u2019Inde? \u00a0Toute la merde se g\u00e8le-t-elle par l\u00e0 ou quoi?<\/p>\n<p>Des odeurs venant de partout ne me laissaient pas me distraire du sujet de leur provenance. Des odeurs\u2026 non, ce ne sont pas des odeurs, c\u2019est de la puanteur, des exhalations f\u00e9tides, infectes, des miasmes!<\/p>\n<p>Mon dieu, c\u2019est quoi qui puisse puer tellement que les larmes viennent aux yeux? \u00a0Le m\u00e9lange de toutes sortes de merde, des produits chimiques acides, des \u00e9manations cadav\u00e9riques, de la poussi\u00e8re \u00e9paisse, et des gaz de combustion, des tas pourrissants interminables des ordures en d\u00e9composition \u2013 c\u2019est avec \u00e7a que les alentours de B\u00e9nar\u00e8s m\u2019accueillent, dans lesquelles le train rampe lentement, comme pour faire expr\u00e8s, en savourant chaque m\u00e8tre. Et pas d\u2019endroit pour ce cacher&#8230; J\u2019avais la gorge prise, j\u2019\u00e9tais d\u00e9j\u00e0 intoxiqu\u00e9e par ce poison jusqu\u2019aux oreilles, non seulement je l\u2019inhalais mais j l\u2019exhalais finalement aussi. La toux d\u00e9chirant la gorge, &#8211; non, il vaut mieux se retenir pour pas tousser, sinon toute cette saloperie m\u2019impr\u00e9gnera compl\u00e8tement. Il n\u2019y a pas longtemps que B\u00e9nar\u00e8s a \u00e9t\u00e9 nomm\u00e9 Varanacy, mais on dirait qu\u2019en Inde on ne peut rien changer d\u2019autres que les noms.<\/p>\n<p>Mes co-passagers, deux femmes Indiennes en face (apparemment, une m\u00e8re et sa fille) continuaient \u00e0 bavarder comme si de rien n\u2019\u00e9tait. On dirait que ce n\u2019\u00e9tait pas possible pour elles de fermer la bouche, &#8211; elles parlaient sans arr\u00eat avec une pause pour dormir la nuit, en restant assises face-\u00e0-face en position turque, en remettant constamment la sari sur la t\u00eate. Ce mouvement est devenu automatique \u2013 notamment, la mise du dernier m\u00e8re du sari sur la t\u00eate en guise de foulard. Les Indiennes de notre \u00e9poque portent le soi-disant penj\u00e2bi, mais ayant renonc\u00e9 au sari, elles n\u2019ont pas pu renoncer \u00e0 ce geste collant (peut-\u00eatre leur donne-t-il le sens de la vie? ), et toutes les dix quinze secondes elles relancent sur une \u00e9paule ou sur l\u2019autre l\u2019\u00e9charpe large qui est tout le temps en train de tomber, port\u00e9e, de toute \u00e9vidence, pour cacher jusqu\u2019au bout les \u00e9paules, le cou et la poitrine des yeux importuns.<\/p>\n<p>O\u00f9 qu\u2019elles se trouvent, les femmes Indiennes, quoi qu\u2019elles fassent, &#8211; les foulards et les \u00e9charpes continuent \u00e0 tomber, et elles les remettent sans y manquer, ne les enlevant m\u00eame pas chez elles (! ), lorsqu\u2019elles font la lessive, lavent le sol, pr\u00e9parent \u00e0 manger. Moi, je p\u00e8terais les plombs de cette n\u00e9cessit\u00e9, mais elles ne le remarquent tout simplement pas.<\/p>\n<p>Le train fait quelques derniers bonds et s\u2019arr\u00eate finalement. Je jette un coup d\u2019\u0153il par la fen\u00eatre aux vitres tint\u00e9es, &#8211; exact, c\u2019est le quai. Des Indiens habill\u00e9s en rouge courent dans la voiture toute de suite, ils recherchent des yeux des clients. Ce sont des porteurs de bagages et je suis pour eux le gibier. Il y en a cinq, debout, \u00e0 c\u00f4t\u00e9 de mon compartiment, en se poussant avec des coudes, en essayant \u00e0 tout prix d\u2019attirer l\u2019attention sur soi, mais il n\u2019est plus possible de m\u2019atteindre. Je suis impassible, froide et s\u00fbre de moi. Hein, les gars\u2026 \u00e9cartez vous, &#8211; je leur montre avec un geste de se casser et je d\u00e9barque sur le quai merdeux (comment peut-il \u00eatre autrement? )<\/p>\n<p>&nbsp;<\/p>\n<p>D\u2019ailleurs, ce n\u2019est le quai qu\u2019en formalit\u00e9, &#8211; pour certains c\u2019est la maison o\u00f9 ils se lavent, dorment, bouffent et r\u00e9fl\u00e9chissent sur les aspects philosophiques d\u00e9licats de vedanta\u2026 je plaisante, bien s\u00fbr) \u2013 ils passent tout simplement leur vies \u00e0 se vautrer sur de paillassons en haillons, en fixant b\u00eatement le chaos de la gare. Ah, j\u2019ai failli oubli\u00e9 \u2013 bien entendu que l\u00e0 ils pissent et chient aussi. Des rats graisseux, des souris aux queues raidies marrantes, des mouches de toutes tailles et couleurs, des chiens au lichen, aux poils tomb\u00e9s, des handicap\u00e9s, des mendiants, des passagers, des cafards de talle de souris, &#8211; tout \u00e7a entrem\u00eal\u00e9s avec du smog caustique et de tapotement des roues. Il faut que je me casse d\u2019ici au plus vite\u2026<\/p>\n<p>A l\u2019entr\u00e9e du b\u00e2timent de la gare \u2013 encore une \u00e9preuve: l\u2019attaque des rickshaws. Ils crient, causent en suppliant, barrent la route, courent devant, et \u00e0 c\u00f4t\u00e9, et derri\u00e8re, en essayant de regarder dans le visage, d\u2019attraper le regard, pour avoir de l\u2019espoir au moins une seconde. Je sais ce qu\u2019il me faut. Je sais ce que je suis pr\u00eate \u00e0 payer. Ca ressemble \u00e0 l\u2019auto training \u2013 les pens\u00e9es \u00e0 haute voix r\u00e9p\u00e8tent les instructions apprises par c\u0153ur de \u00abLonely Planet\u00bb Je n\u2019en d\u00e9mordrai pas.<\/p>\n<p>&#8211; Cinquante roupies pour aller \u00e0 Shivala gat.<\/p>\n<p>&#8211; Cette voiture, non celle l\u00e0, mam. Shivala gat, cinquante roupies, mam! &#8211; la foule inqui\u00e8te de rickshaws a gueul\u00e9 en une seule voix. Quelqu\u2019un commence m\u00eame \u00e0 me tirer par le sac \u00e0 dos, de peur de toucher mon corps.<\/p>\n<p>Je choisis parmi eux un gars mince et de petite taille, qui ne d\u00e9montre pas d\u2019activit\u00e9 effr\u00e9n\u00e9e, comme s\u2019il pensait \u00e0 autre chose. J\u2019ai voulu en rajouter comme quoi il \u00e9tait amoureux ou d\u00e9vou\u00e9 \u00e0 une religion quelconque. Je lui fais un hochement de la t\u00eate pour montrer que je vais avec lui.<\/p>\n<p>&#8211; O\u00f9 est ta voiture?<\/p>\n<p>Il indique avec son doigt une petite caisse-scarab\u00e9e noire sur de petites roues, et tous les autres vas nu-pieds, perdant \u00e0 cette loterie, se cassent, les mines d\u00e9\u00e7ues. Mais \u00e0 peine j\u2019ai eu le temps de monter dans la voiture qu\u2019ils m\u2019ont d\u00e9j\u00e0 oubli\u00e9e, moi et leur \u00e9chec, &#8211; ainsi est leur vie, dans une telle lutte chaque jour passe. Jamais rien de nouveau, et la puanteur horrible, entrem\u00eal\u00e9e \u00e0 des proportions infernales avec de la canicule gluante, n\u2019est pour eux que de l\u2019air ordinaire imperceptible.<\/p>\n<p>La bagnole, une fois le moteur allum\u00e9, commence \u00e0 trembler tr\u00e8s fort, en faisant un barouf assommant, ensuite elle se lance en avant, avec un d\u00e9fi digne de Schumarer, &#8211; dans le m\u00e9li-m\u00e9lo chaotique du trafic. De l\u2019air chaud et sale et des coups d\u2019\u0153il insistants de tous les c\u00f4t\u00e9s s\u2019engouffrent dans mon petit abri\u2026 Normalement, la route ne doit pas \u00eatre longue. Je suis press\u00e9e de me mettre sous une douche fra\u00eeche. Aucune envie de regarder dehors \u2013 toutes les villes indiennes sont mis\u00e9rables et moches de mani\u00e8re absolument identique, sauf des endroits o\u00f9 les monuments historiques et des lieux \u00e0 int\u00e9r\u00eat touristique sont concentr\u00e9s. A moins qu\u2019on aspire \u00e0 monter le taux d\u2019adr\u00e9naline dans le sang, l\u2019Inde n\u2019est pas un pays pour exp\u00e9rimenter, ici il faut suivre \u00e0 la lettre les recommandations du guide et les conseils de ceux qui ont d\u00e9j\u00e0 acquis l\u2019exp\u00e9rience de voyager dans ce pays.<\/p>\n<p>Alors B\u00e9nar\u00e8s sacr\u00e9 ne diff\u00e9rencie en rien pour l\u2019instant d\u2019une n\u2019importe quelle petite ville. Je n\u2019imagine pas comment on peut vivre ici\u2026 Je me suis souvenue qu\u2019une fois \u00e0 Moscou lors d\u2019un s\u00e9minaire sur yoga un professeur d\u00e9bile a dit, l\u2019air pensif, qu\u2019il avait un r\u00eave &#8211; laisser tout tomber et aller s\u2019installer dans un ashram \u00e0 B\u00e9nar\u00e8s, mais son karma ne lui permettais pas pour le moment m\u00eame d\u2019aller en Inde voir son professeur. A ce moment l\u00e0 il ne me paraissait pas d\u00e9bile bien \u00e9videmment, et les mots \u00abB\u00e9nar\u00e8s\u00bb, \u00abMa\u00eetre\u00bb, \u00abAshram\u00bb me faisaient trembler d\u2019anticipation \u2013 Ca existe quelque part.<\/p>\n<p>La ville de Siva, le dieu de la mort dans l\u2019hindouisme, au bord du Gange sacr\u00e9, &#8211; ici les vieux croyants se pr\u00e9cipitent pour attendre la mort. Etre br\u00fbl\u00e9 \u00e0 B\u00e9nar\u00e8s, au bord du Gange, &#8211; c\u2019est, selon leur croyance, le point mis apr\u00e8s un milliard de renaissances, la cessation de karma, la fusion avec Siva. Comme tout est simple\u2026 Peu importe comment on a v\u00e9cu sa vie, ce que l\u2019on a fait et senti, &#8211; rien n\u2019importe, except\u00e9 le fait que le corps a \u00e9t\u00e9 br\u00fbl\u00e9 justement ici. Il faut \u00eatre aussi infantiles pour vivre des croyances tellement primitives! \u00a0Ou bien ces croyances apparaissent justement d\u00fb aux caract\u00e9ristiques sp\u00e9cifiques de la nation? .. Combien de temps peut encore durer cette route, qui secoue l\u2019\u00e2me? &#8230; Et non, l\u2019hindouisme ne me plait d\u00e9finitivement pas, &#8211; les plus distincts deviennent les d\u00e9tailles de ce ph\u00e9nom\u00e8ne, le moins il me plait. Je ne vais pas rester longtemps \u00e0 Varanacy.<\/p>\n<p>Ouf, finalement! \u00a0L\u2019immeuble ressemblant partiellement \u00e0 un b\u00e2timent europ\u00e9en est mon h\u00f4tel. Le nom est lyrique \u2013 \u00abSunrise Hotel\u00bb\u2026 Les pousses de l\u2019humidit\u00e9 et de salet\u00e9 ont d\u00e9j\u00e0 commenc\u00e9 \u00e0 l\u2019entortiller, et dans dix ans il fusionnera en extase avec la jungle faite de pierre et d\u2019ordures que la langue ne bouge pas pour appeler une ville.<\/p>\n<p>A l\u2019int\u00e9rieur la m\u00eame humidit\u00e9 et l\u2019odeur particuli\u00e8re, qui commence \u00e0 se faire sentir dans l\u2019a\u00e9roport indien et qui impr\u00e8gne tout ici, tout ce que les Indiens touchent. Un petit gars pel\u00e9 sort \u00e0 ma rencontre\u2026 la bouche en sang! \u00a0Qu\u2019est-ce qu\u2019il a? \u00a0On dirait qu\u2019il a la bouche pleine de sang, il n\u2019arrive m\u00eame pas \u00e0 parler normalement \u2013 il rejette la t\u00eate en arri\u00e8re, les paroles passent \u00e0 travers le bourdonnement d\u00e9go\u00fbtant (qui appeler? \u00a0la police? \u00a0les urgences? ) \u2026 c\u2019est bizarre, mais cela n\u2019\u00e9tonne personne, personne n\u2019y fait attention! \u00a0Merde\u00a0\u2026 encore un avec la bouche pareille, il crache abondamment le liquide rouge sur le bitume. J\u2019ai la naus\u00e9e, je me retourne\u2026 Encore un autre sort \u00e0 ma rencontre, apparemment un employ\u00e9 de l\u2019h\u00f4tel. On ne saurait jamais distinguer un employ\u00e9 d\u2019un passant ordinaire, &#8211; tout le monde est sale de la m\u00eame mani\u00e8re, aux yeux tout \u00e0 fait pareils \u2013 en verre, juste comme ceux des poup\u00e9es. On ne voit presque pas les pupilles\u2026 bon sang, ils font penser aux vampires.<\/p>\n<p>Plus tard j\u2019ai appris que beaucoup d\u2019Indiens sont toxicos du b\u00e9tel \u2013 c\u2019est une sorte de drogue douce qui se vend l\u00e9galement \u00e0 chaque coin de la rue. Le bitume dans toutes les rues de B\u00e9nar\u00e8s, ainsi que les murs de beaucoup de maisons au niveau de la taille humaine rougissent de la salive, empoisonn\u00e9e par le b\u00e9tel. Cette ville se noie tout simplement dans le b\u00e9tel, brillant dans les reflets des yeux vitrifi\u00e9s!<\/p>\n<p>Ma chambre s\u2019est av\u00e9r\u00e9e ordinaire \u2013 aux murs sales, avec des draps gris, un ventilateur furieux, au sol en pierre, avec une table poussi\u00e9reuse instable, une chaise inconfortable\u2026 Un coin o\u00f9 on ne peut que dormir. La porte qui m\u00e8ne sur le balcon et les volets sont condamn\u00e9s. Je force d\u00e9cid\u00e9ment les obstacles vers l\u2019air frais\u2026 zut, j\u2019ai oubli\u00e9 o\u00f9 je me retrouvais\u2026 la fum\u00e9e chaude et \u00e9touffante s\u2019engouffre de la rue. Je verouille tout de nouveau. Par contre, il y a de l\u2019eau chaude, et m\u00eame la t\u00e9l\u00e9 est propos\u00e9e pour un dollar par jour. Je dis que je n\u2019en ai pas besoin m\u00eame gratuit, finalement, je me retrouve toute seule, dans le silence relatif, isol\u00e9e du monde ext\u00e9rieur violeur.<\/p>\n<p>Je me demande pourquoi il y a des fen\u00eatres donnant des chambres dans le couloir? \u2026 Si l\u2019on essayait de fermer cette fen\u00eatre\u2026 et en tapant avec le poing sur les volets\u00a0\u2026 Ca y est, c\u2019est mieux comme \u00e7a\u2026 Et pourquoi je pense \u00e0 toute sorte de b\u00eatise? \u00a0Mais comment faire? \u00a0Parfois les pens\u00e9es se calment un peu, mais d\u2019autres fois elles deviennent folles, et alors la grisaille agit\u00e9e couvre tout. Je me sens comme un pot attach\u00e9 \u00e0 la queue d\u2019un chat \u2013 les pens\u00e9es courent et je cours apr\u00e8s elles en tonnant contre le bitume de mani\u00e8re \u00e0 faire boucher les oreilles\u2026 Cette grisaille ressemble \u00e0 de la faiblesse physique, &#8211; on contracte un muscle pour faire un mouvement, et il se d\u00e9tend tout de suite\u2026 Mais le plus horrible est qu\u2019il y a dans cet \u00e9tat gris meurtri \u00abson propre attrait\u00bb, je prends plaisir \u00e0 devenir ce kissel pourri. J\u2019ai essay\u00e9 d\u2019imaginer que juste maintenant je peux appuyer sur un bouton pour commencer \u00e0 ressentir l\u2019\u00e9nergie, la concentration\u2026 Un cauchemar!!! Mais avec \u00e7a je NE VEUX aucun changement. Je ne veux donc rien changer\u2026 je veux et je ne veux pas, et rien ne r\u00e9ussit justement \u00e0 cause de \u00e7a\u2026 c\u2019est pourquoi le m\u00e9contentement arrive, lorsqu\u2019on se force de faire ce qu\u2019on ne veux pas. Non \u2013 c\u2019est quand on se force de faire ce qu\u2019on veut et ce qu\u2019on ne veut pas en m\u00eame temps. C\u2019est du d\u00e9lire\u2026 Comment est-ce possible, que je choisis moi-m\u00eame cette stupidit\u00e9 au lieu de la concentration? \u00a0Et \u00e7a veut dire quoi \u00abje veux\u00bb et \u00abje ne veux pas\u00bb en m\u00eame temps? \u00a0Ce n\u2019est pas possible, encore je ne comprends pas quelque chose quelque part, je me trompe quelque part dans mes r\u00e9flexions. Comment puis-je m\u2019installer ici\u2026 En avan\u00e7ant cette petite table vers le lit\u2026 mettre le calepin dessus \u2013 j\u2019ai une sorte de bureau de travail dans une prison bien am\u00e9nag\u00e9e \u2013 et ben, pas mal du tout! \u00a0D\u2019abord, il vient l\u2019horreur d\u2019une bonne femme au foyer \u2013 comment peut-on vivre, faire des recherches, \u00e9crire dans de TELLES conditions, mais en regardant consciemment et raisonnablement\u2026 des conditions tout \u00e0 fait convenables \u2013 rien ne distrait l\u2019attention, je peux me concentrer totalement sur mes affaires. Je ne m\u2019attendais pas du tout de prendre plaisir des conditions prisonni\u00e8res.<\/p>\n<p>Bien, je retourne en arri\u00e8re \u2013 qu\u2019est-ce que j\u2019\u00e9prouve en ce moment? \u00a0Est-ce que je souhaite changer mon \u00e9tat ou pas? \u00a0Mais non, m\u00eame pas \u00e7a. \u00abChanger\u00bb &#8211; c\u2019est quelque chose d\u2019actif, maintenant la question n\u2019est pas l\u00e0. Est-ce que je veux que tout de suite en appuyant sur le bouton la grisaille disparaisse toute seule? \u00a0Non, je ne veux pas. Mais si, je veux! \u00a0Et en m\u00eame temps je ne le veux pas. Mais qu\u2019est-ce que c\u2019est que \u00e7a\u2026 c\u2019est idiot! \u00a0Je n\u2019arrive pas \u00e0 me d\u00e9cider \u2013 si je veux quelque chose maintenant ou pas? \u00a0Comment puis-je voir clair en quelque chose de plus compliqu\u00e9 si je n\u2019arrive m\u00eame pas \u00e0 comprendre une chose aussi simple! \u00a0Alors, je le veux ou pas?! \u00a0Je veux. Non, je ne veux pas. Si, je veux. Ce n\u2019est pas possible\u2026 Mais pourquoi \u2026 pourquoi ce n\u2019est pas possible? \u00a0Il me semble que je viens de trouver le crapaud qui m\u2019emp\u00eache de vivre\u2026 &#8211; ce \u00abpas possible\u00bb. Pourquoi est-ce je m\u2019obstine avec ce \u00abpas possible\u00bb? \u00a0Il faut avoir le courage d\u2019admettre les faits, et le fait est que je veux et je ne veux pas en m\u00eame temps. Mais il s\u2019av\u00e8re une chose bizarre alors \u2013 si justement maintenant je veux, qui ne veut pas donc justement maintenant? \u00a0Et si, en r\u00e9alit\u00e9, je ne veux pas &#8211; qui veut justement maintenant? \u00a0Qui veut? \u00a0Qui ne veut pas? \u00a0Cette question est un peu plus int\u00e9ressante\u2026 Qui? \u00a0Et c\u2019est quoi \u00abqui\u00bb? \u00a0\u2026 et oui\u2026 l\u2019impasse. Encore une impasse. Bien, il me reste de revenir \u00e0 ce que je per\u00e7ois. Le fait est le m\u00eame \u2013 il y a deux d\u00e9sirs simultan\u00e9s \u2013 ind\u00e9pendamment de ce que c\u2019est ce \u00abqui\u00bb. Il se trouve alors\u2026 et oui, c\u2019est une balance, qui p\u00e8se plus lourd \u2013 c\u2019est ce qui est. C\u2019est quoi exactement qui m\u2019\u00e9tonne? \u00a0En ce moment je veux aller pisser, aller me promener vers le Gange, et rester ici pour r\u00e9fl\u00e9chir encore. Mais c\u2019est tout le temps comme \u00e7a, il y a plusieurs d\u00e9sirs constamment, et par cons\u00e9quent, il arrive ce qui est le r\u00e9sultat de ces forces \u2013 si le poisson, l\u2019\u00e9crevisse et le brochet vont tirer ma bassine dans des directions diff\u00e9rentes avec des forces diff\u00e9rentes, cette derni\u00e8re va bouger quelque part quand m\u00eame. La question donc se pose autrement \u2013 peut-on renforcer un d\u00e9sir et att\u00e9nuer un autre? \u00a0Oh! &#8230; zut, \u00e7a c\u2019est de la jungle.<\/p>\n<p>On frappe \u00e0 la porte \u2013 quoi encore? \u00a0Le passeport? \u00a0Ah, oui le passeport\u2026 plus tard, j\u2019ai dit plus tard! \u00a0J\u2019apporterai moi-m\u00eame mon passeport, oui, plus tard, je l\u2019apporterai moi-m\u00eame, oui, \u00e0 la r\u00e9ception, je sais, oui\u2026<\/p>\n<p>Bien, il existe alors plusieurs d\u00e9sirs \u2013 justement maintenant. Encore un qui s\u2019est rajout\u00e9 \u2013 apporter mon passeport \u00e0 la r\u00e9ception. Chaque d\u00e9sir n\u2019a pas apparu de nulle part. J\u2019ai envie de pisser, parce que la vessie met de la pression sue le cerveau \u2013 rien \u00e0 faire avec cette sensation, elle am\u00e8ne aux toilettes avec insistance. C\u2019est plut\u00f4t que je comprends qu\u2019en allant aux toilettes, je me d\u00e9barrasserai de cette sensation\u2026 l\u00e0 c\u2019est clair. Je veux aller me promener vers le Gange, parce que je veux obtenir des impressions, c\u2019est la curiosit\u00e9 qui me pousse, et pas que, de l\u2019ennui aussi, bien entendu, puisque si je ne m\u2019ennuyais pas, il n\u2019y aurait pas alors de cette fougue particuli\u00e8re dans le d\u00e9sir d\u2019aller voir. Je connais la diff\u00e9rence entre un d\u00e9sir joyeux et calme et des spasmes accrochants, qu\u2019on ne peut m\u00eame pas appeler d\u00e9sirs. Justement maintenant il est spasmodique, parce que autour il n\u2019y a pas d\u2019ensemble d\u2019impressions habituel \u2013 que des murs nus et moi-m\u00eame avec mon calepin. Il y a le d\u00e9sir d\u2019apporter le passeport \u2013 il est amen\u00e9 par la politesse \u2013 on m\u2019attend par l\u00e0\u2026 et bien s\u00fbr que c\u2019est une connerie, parce que personne ne m\u2019attends par l\u00e0, ils n\u2019attendent jamais personne en g\u00e9n\u00e9ral, en flottant dans la substance en b\u00e9tel sans indent\u00e9, mais l\u2019inqui\u00e9tude ne passe pas \u2013 je suis habitu\u00e9e, on m\u2019a appris\u2026 Il y a le d\u00e9sir de comprendre \u2013 \u00abqui veut alors\u00bb. Ce d\u00e9sir est le plus vif \u2013 Il est accompagn\u00e9 par l\u2019anticipation, l\u2019int\u00e9r\u00eat, je tire un vrai plaisir de mes efforts malhabiles.<\/p>\n<p>Bien, je vais mettre de c\u00f4t\u00e9 la question \u00abqui veut\u00bb &#8211; je n\u2019ai aucune id\u00e9e comment y r\u00e9pondre, quoi que la contradiction soit \u00e9vidente \u2013 si \u00abje\u00bb veux une chose, comment puis-\u00bbje\u00bb en vouloir une autre en m\u00eame temps? \u00a0Ou alors c\u2019est simplement le d\u00e9placement de l\u2019attention entre les d\u00e9sirs? \u00a0Je peux bien voir en m\u00eame temps la table, et le calepin, et les murs \u2013 je sais qu\u2019on a fait une exp\u00e9rience suivante: on a coll\u00e9 un appareil sp\u00e9cial sur la pupille qui refl\u00e9tait le rayon du laser, et quand la personne \u00abregardait simplement une table\u00bb, en voyant tous les objets \u00absimultan\u00e9ment\u00bb, il s\u2019est av\u00e9r\u00e9 que sa pupille faisait une \u00e9norme quantit\u00e9 de mouvements microscopiques \u2013 \u00e0 la vitesse incroyable le regard scannait l\u2019espace qui se trouvait dans son champ de vision, c\u2019est pourquoi on croit qu\u2019on voit tout en m\u00eame temps. Ainsi, peut-\u00eatre, \u00e7a se fait avec des d\u00e9sirs et d\u2019autres choses \u2013 en m\u00eame temps on peut penser \u00e0 deux choses, voir la pi\u00e8ce, vouloir ceci et cela \u2013 c\u2019est tout simplement l\u2019attention qui passe d\u2019une chose \u00e0 une autre aussi vite. Bon, finalement, cette explication peut \u00eatre la bonne, ou bonne \u00e0 moiti\u00e9, ou compl\u00e8tement erron\u00e9e, au diable \u2013 je n\u2019ai pas besoin d\u2019explication, j\u2019ai besoin d\u2019autre chose. Comment renforcer un d\u00e9sir pour qu\u2019il remporte sur les autres?<\/p>\n<p>Comment renforcer\u2026 mais \u00abqui\u00bb va le faire? \u00a0Oh! &#8230; c\u2019est justement \u00abquelqu\u2019un\u00bb qui doit le faire, mais \u00abqui\u00bb? \u00a0\u00abMoi\u00bb? \u00a0Et c\u2019est qui \u00abmoi\u00bb? \u00a0Et pourquoi ce\u00bbmoi\u00bb renforcera justement ce d\u00e9sir? \u00a0Sinon? &#8230; Fini\u2026 Une impasse.<\/p>\n<p>J\u2019essaie de changer quelque chose au moins en apparence \u2013 je prends une autre position, je redresse les \u00e9paules, je fais une autre expression du visage, et le plus longtemps je reste comme \u00e7a, le moins confortable je me sens. Le lit s\u2019approche, en m\u2019attirant avec l\u2019oreiller et le dossier sur lequel on peut s\u2019appuyer\u2026 Ca y est. Maintenant aucune force au monde ne me fera me relever, maintenant je veux rester couch\u00e9e. Juste il ne faut pas penser \u00e0 ce qui vient de se passer, sinon je ne pourrais pas rester couch\u00e9e tranquillement. La bataille contre la grisaille est perdue, elle m\u2019a emp\u00eatr\u00e9e, engloutie, en essayant de me diluer sans r\u00e9sidu dans l\u2019oubli sale et opaque. Se piquer et s\u2019oublier\u2026 la grisaille \u2013 la drogue la plus puissante.<\/p>\n<p>J\u2019ai remarqu\u00e9 de maintes fois, que quand je me retrouve dans un nouvel endroit, pendant les premiers jours les nouvelles impressions m\u2019assourdissent si fortement, que je cesse d\u2019exister compl\u00e8tement, je dirais, pendant ce temps, &#8211; il ne reste pas de d\u00e9sirs habituels, ni d\u2019\u00e9motions, ni m\u00eame de sensations, &#8211; le vide gris, l\u2019indiff\u00e9rence, le saisi spasmodique des impressions \u2013 encore et encore. Ensuite, le plaisir des impressions commence \u00e0 r\u00e9duire, se change en fatigue, le d\u00e9sir de me reposer, rester toute seule avec moi-m\u00eame, et parall\u00e8lement je commence \u00e0 revivre, les d\u00e9sirs reviennent, ainsi que l\u2019int\u00e9r\u00eat envers la vie. Je me demande c\u2019est \u00e0 cause de quoi? \u00a0Cela ressemble \u00e0 l\u2019empoisonnement\u2026 Les premiers jours l\u2019attention se d\u00e9chire en morceaux malgr\u00e9 mon envie. Mon envie, le mien\u2026 c\u2019est qui alors qui veut des impressions? \u00a0Encore les m\u00eames billeves\u00e9es\u2026 Je dois savoir o\u00f9 je me trouve, je d\u00e9visage tout alors, bien que ce soit plus exacte de dire que ce n\u2019est pas moi qui d\u00e9visage quelque chose, mais le regard colle \u00e0 chaque d\u00e9tail, les pens\u00e9es n\u2019arr\u00eatent pas de sucer ce qui est vu, comme des araign\u00e9es elles tissent leur toile vite, vite, &#8211; ainsi se compose le tableau du nouvel endroit. Aucune id\u00e9e comment peut-on y r\u00e9sister? \u00a0Et si l\u2019on ne regardait pas autour? &#8230; Comme si j\u2019ai jet\u00e9 un coup d\u2019\u0153il dans le n\u00e9ant\u2026 Je m\u2019imagine me trouver dans un nouvel endroit sans regarder autour, sans savoir comment est le monde autour. C\u2019est incroyable! \u00a0L\u00e0 je touche \u00e0 quelque chose\u2026 Je jette un regard derri\u00e8re l\u2019image du monde, et derri\u00e8re \u2013 l\u2019\u00e9l\u00e9ment impitoyable, bouillonnant, r\u00e9duisant en poussi\u00e8re tout ce qui le touche, ne serait-ce qu\u2019\u00e0 peine.<\/p>\n<p>\u2026 Plus d\u2019envie de rester couch\u00e9e. C\u2019est \u00abmoi\u00bb qui ne veux plus rester couch\u00e9e ou bien \u00able soi-m\u00eame\u00bb qui ne veut pas? \u00a0Si c\u2019est \u00able soi-m\u00eame\u00bb &#8211; o\u00f9 suis moi alors et comment ce \u00abmoi\u00bb peut influencer quelque chose? \u00a0J\u2019en ai assez de cette question! \u00a0\u00abJe, moi\u00bb? \u00a0\u00abQui\u00bb en a assez?? Et oui\u2026 on peut devenir fou comme \u00e7a. Il n\u2019est que deux heures de l\u2019apr\u00e8s-midi, le pic de la chaleur, devrais-je aller me promener sur le quai fameux? \u00a0Le sujet \u00e0 la r\u00e9ception (qui c\u2019est d\u2019ailleurs \u2013 un employ\u00e9 ou un passant de hasard \u2013 diable sait\u2026) commence \u00e0 verser des torrents de mots comme quoi j\u2019ai eu de la chance, parce que demain il y aura une grande f\u00eate, et que c\u2019est le meilleur moment pour commander une escapade matinale sur un bateau, et ensuite aller se balader dans les quartiers musulmans pour voir comment ils font de la soie \u00e0 la main.<\/p>\n<p>&#8211; Demain matin, \u00e0 l\u2019aube, vous pourrez voir beaucoup de gens venir au bord du<\/p>\n<p>Gange pour se baigner dans l\u2019eau sacr\u00e9e, prier et faire des dons \u00e0 la rivi\u00e8re. Et ce n\u2019est que demain pour une journ\u00e9e que les ma\u00eetres de la soie ouvriront les fen\u00eatres de ses ateliers pour des observateurs ext\u00e9rieurs, c\u2019est un spectacle tr\u00e8s int\u00e9ressant. Vous pourrez faire de rares photos\u2026 Alors, demain \u00e0 cinq heures je vous attends ici.<\/p>\n<p>Chouette! \u00a0J\u2019aurai un tas d\u2019impressions. Qu\u2019est-ce que quelqu\u2019un dans la t\u00eate me marmotte? \u00a0Ne pas c\u00e9der \u00e0 l\u2019hypnose et ne pas croire aux promesses? \u00a0Bon, alors\u2026 si je m\u2019ennuie \u2013 je rentre. Plus tard j\u2019ai vu qu\u2019il tenait ce discours devant chaque nouveau venu \u2013 j\u2019ai eu l\u2019occasion de l\u2019observer avec mes propres yeux, en plus il le faisait absolument sans vergogne, sans faire aucune attention \u00e0 ce que j\u2019assistais \u00e0 ce cirque.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans aucun trou du cul du monde il ne pue autant qu\u2019en Inde. J\u2019ai toujours \u00e9t\u00e9 sensible aux odeurs comme un animal\u00a0d\u00e9licat. Le m\u00e9tro, des petits bus bond\u00e9s, des ascenseurs sont les endroits de mes tortures olfactives: ce mec a mang\u00e9 du fromage amer ce matin, et cette bonne femme l\u00e0 s\u2019est arros\u00e9e avec un [&hellip;]<\/p>\n","protected":false},"author":8235,"featured_media":0,"parent":7693,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9563","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chapitre 27 - Selection of Attractive States<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chapitre 27 - Selection of Attractive States\" \/>\n<meta property=\"og:description\" content=\"Dans aucun trou du cul du monde il ne pue autant qu\u2019en Inde. J\u2019ai toujours \u00e9t\u00e9 sensible aux odeurs comme un animal\u00a0d\u00e9licat. Le m\u00e9tro, des petits bus bond\u00e9s, des ascenseurs sont les endroits de mes tortures olfactives: ce mec a mang\u00e9 du fromage amer ce matin, et cette bonne femme l\u00e0 s\u2019est arros\u00e9e avec un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/\" \/>\n<meta property=\"og:site_name\" content=\"Selection of Attractive States\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-27\\\/\",\"url\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-27\\\/\",\"name\":\"Chapitre 27 - Selection of Attractive States\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/#website\"},\"datePublished\":\"2015-03-18T17:39:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-27\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-27\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/chapitre-27\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMAYA\u00bb. Livre 1: Force mineure\",\"item\":\"https:\\\/\\\/bodhi.name\\\/fr\\\/maya-livre-1\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chapitre 27\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/\",\"name\":\"Selection of Attractive States\",\"description\":\"Psychologie exp\u00e9rimentale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodhi.name\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chapitre 27 - Selection of Attractive States","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/","og_locale":"fr_FR","og_type":"article","og_title":"Chapitre 27 - Selection of Attractive States","og_description":"Dans aucun trou du cul du monde il ne pue autant qu\u2019en Inde. J\u2019ai toujours \u00e9t\u00e9 sensible aux odeurs comme un animal\u00a0d\u00e9licat. Le m\u00e9tro, des petits bus bond\u00e9s, des ascenseurs sont les endroits de mes tortures olfactives: ce mec a mang\u00e9 du fromage amer ce matin, et cette bonne femme l\u00e0 s\u2019est arros\u00e9e avec un [&hellip;]","og_url":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/","og_site_name":"Selection of Attractive States","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/","url":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/","name":"Chapitre 27 - Selection of Attractive States","isPartOf":{"@id":"https:\/\/bodhi.name\/ru\/#website"},"datePublished":"2015-03-18T17:39:14+00:00","breadcrumb":{"@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bodhi.name\/fr\/maya-livre-1\/chapitre-27\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/bodhi.name\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00abMAYA\u00bb. Livre 1: Force mineure","item":"https:\/\/bodhi.name\/fr\/maya-livre-1\/"},{"@type":"ListItem","position":3,"name":"Chapitre 27"}]},{"@type":"WebSite","@id":"https:\/\/bodhi.name\/ru\/#website","url":"https:\/\/bodhi.name\/ru\/","name":"Selection of Attractive States","description":"Psychologie exp\u00e9rimentale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodhi.name\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/users\/8235"}],"replies":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":1,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9563\/revisions"}],"predecessor-version":[{"id":9565,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/9563\/revisions\/9565"}],"up":[{"embeddable":true,"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/pages\/7693"}],"wp:attachment":[{"href":"https:\/\/bodhi.name\/fr\/wp-json\/wp\/v2\/media?parent=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}